{"id":1816,"date":"2025-08-20T10:38:15","date_gmt":"2025-08-20T13:38:15","guid":{"rendered":"https:\/\/lam.unitedforclinicalnutrition.com\/pt-br\/?p=1816"},"modified":"2025-08-20T12:14:59","modified_gmt":"2025-08-20T15:14:59","slug":"diferentes-aminoacidos-nutricao-parenteral","status":"publish","type":"post","link":"https:\/\/lam.unitedforclinicalnutrition.com\/pt-br\/diferentes-aminoacidos-nutricao-parenteral\/","title":{"rendered":"Vantagens no uso de diferentes amino\u00e1cidos na nutri\u00e7\u00e3o parenteral"},"content":{"rendered":"<p>O fornecimento de amino\u00e1cidos na nutri\u00e7\u00e3o parenteral \u00e9 um dos fatores mais importantes no suporte nutricional. Nesse sentido, existem diversos tipos de amino\u00e1cidos, que exercem fun\u00e7\u00f5es espec\u00edficas no organismo.<\/p>\n<p>A seguir, vamos entender como eles se dividem e como podem ser usados para as diferentes necessidades dos pacientes que precisam de nutri\u00e7\u00e3o parenteral.<\/p>\n<h2><strong>Papel dos amino\u00e1cidos no organismo<\/strong><\/h2>\n<p>Os amino\u00e1cidos s\u00e3o as unidades estruturais das prote\u00ednas, que sustentam processos qu\u00edmicos vitais.<\/p>\n<p>Entre as fun\u00e7\u00f5es que eles desempenham no organismo, podemos destacar (1):<\/p>\n<ul>\n<li>Constru\u00e7\u00e3o de m\u00fasculos, \u00f3rg\u00e3os, gl\u00e2ndulas, ligamentos, tend\u00f5es, unhas, cabelos e ossos;<\/li>\n<li>Horm\u00f4nios e enzimas;<\/li>\n<li>Regula\u00e7\u00e3o de vias metab\u00f3licas fundamentais para a imunidade, reprodu\u00e7\u00e3o, manuten\u00e7\u00e3o e crescimento (papel exercido pelos amino\u00e1cidos funcionais: arginina, ciste\u00edna, glutamina, leucina, prolina e triptofano);<\/li>\n<li>\u00danica fonte de nitrog\u00eanio;<\/li>\n<li>Preserva\u00e7\u00e3o da estrutura celular, cicatriza\u00e7\u00e3o de feridas, heran\u00e7a enzim\u00e1tica e hormonal, j\u00e1 que n\u00e3o temos estoque no organismo e dependemos das prote\u00ednas externas em quantidade e qualidade para compensar as perdas di\u00e1rias.\n<p>Os amino\u00e1cidos se dividem entre (2):<\/li>\n<li><strong>Amino\u00e1cidos essenciais<\/strong>: n\u00e3o s\u00e3o sintetizados pelo organismo e, portanto, precisam ser consumidos.<\/li>\n<li><strong>Amino\u00e1cidos n\u00e3o essenciais<\/strong>: s\u00e3o sintetizados a partir de mol\u00e9culas de carboidratos intracelulares e grupos amina.<\/li>\n<li><strong>Amino\u00e1cidos semi-essenciais ou condicionalmente essenciais<\/strong>: podem ser sintetizados a partir de outros amino\u00e1cidos em certas circunst\u00e2ncias, mas sua s\u00edntese \u00e9 limitada.<\/li>\n<\/ul>\n<h2><strong>Papel dos amino\u00e1cidos na nutri\u00e7\u00e3o parenteral<\/strong><\/h2>\n<p>A defici\u00eancia de prote\u00edna e energia \u00e9 comum em pacientes hospitalizados e naqueles que apresentam estado cr\u00edtico.<\/p>\n<p>Al\u00e9m disso, muitas doen\u00e7as e tratamentos alargam significativamente as necessidades de prote\u00edna do organismo ou provocam um aumento patol\u00f3gico do catabolismo (consumo) de prote\u00ednas musculares. S\u00e3o exemplos de situa\u00e7\u00f5es em que isso ocorre a terapia com altas doses de glicocorticoides e a resposta inflamat\u00f3ria sist\u00eamica \u00e0 sepse e a grandes traumas (3).<\/p>\n<p>Como consequ\u00eancia desses quadros, pacientes hospitalizados podem sofrer atrofia muscular generalizada. Essa altera\u00e7\u00e3o \u00e9 debilitante, dif\u00edcil de reverter e representa uma amea\u00e7a \u00e0 vida (3).<\/p>\n<p>Assim, a nutri\u00e7\u00e3o parenteral busca oferecer quantidades significativas, mas n\u00e3o t\u00f3xicas, de prote\u00ednas, sendo ferramenta importante no alcance desse objetivo (3).<\/p>\n<p>Nos pacientes em nutri\u00e7\u00e3o parenteral, a ingest\u00e3o de prote\u00ednas \u00e9 atendida pelo fornecimento de solu\u00e7\u00f5es est\u00e9reis intravenosas de amino\u00e1cidos livres. As solu\u00e7\u00f5es padr\u00e3o cont\u00eam amino\u00e1cidos essenciais, alguns amino\u00e1cidos n\u00e3o essenciais e, ocasionalmente alguns amino\u00e1cidos semi-essenciais (1).<\/p>\n<p>Essa composi\u00e7\u00e3o busca fornecer ao organismo os elementos necess\u00e1rios para o balan\u00e7o energ\u00e9tico e proteico, al\u00e9m de atingir a quantidade necess\u00e1ria de nitrog\u00eanio (1).<\/p>\n<p>Em situa\u00e7\u00f5es cl\u00ednicas espec\u00edficas (ex.: erro no metabolismo de algum amino\u00e1cido), rec\u00e9m- nascidos prematuros e pacientes cr\u00edticos, solu\u00e7\u00f5es especializadas podem ser necess\u00e1rias (4).<\/p>\n<h2><strong>Amino\u00e1cidos de destaque<\/strong><\/h2>\n<p>O aumento de massa muscular esquel\u00e9tica requer uma quantidade efetiva de amino\u00e1cidos essenciais, principalmente leucina, isoleucina e metionina, que, em dose adequada, desencadeiam uma resposta anab\u00f3lica e, portanto, o crescimento muscular (1).<\/p>\n<p>Entre os amino\u00e1cidos n\u00e3o essenciais, parece que a contribui\u00e7\u00e3o espec\u00edfica de cada um desses amino\u00e1cidos nas formula\u00e7\u00f5es parenterais \u00e9 menos importante que a quantidade total de nitrog\u00eanio que, juntos, eles fornecem (3).<\/p>\n<p>Alguns amino\u00e1cidos se destacam por seu papel na nutri\u00e7\u00e3o dos pacientes que dependem da terapia parenteral. Confira a seguir.<\/p>\n<h5><strong>Tirosina<\/strong><\/h5>\n<p>A tirosina se torna essencial para \u00f3rg\u00e3os e tecidos que n\u00e3o possuem a fenilalanina hidroxilase, enzima que converte a fenilalanina em tirosina. Assim, a adi\u00e7\u00e3o de tirosina a outros amino\u00e1cidos essenciais melhoraria a efic\u00e1cia de sua s\u00edntese (1).<\/p>\n<p>A concentra\u00e7\u00e3o de tirosina em misturas de amino\u00e1cidos \u00e9 limitada por sua baixa solubilidade, por\u00e9m, como colocado anteriormente, ela pode ser sintetizada a partir da fenilalanina.<\/p>\n<p>Se a oferta de fenilalanina for suficiente e o paciente que estiver com balan\u00e7o nitrogenado neutro ou negativo e com a convers\u00e3o de fenilalanina em tirosina desimpedida, a necessidade de tirosina ser\u00e1 atendida apenas pela fenilalanina (3).<\/p>\n<h5><strong>Ciste\u00edna <\/strong><\/h5>\n<p>A ciste\u00edna \u00e9 um amino\u00e1cido importante na s\u00edntese de prote\u00ednas e taurina, bem como para a s\u00edntese de glutationa. A glutationa \u00e9 uma pedra angular na manuten\u00e7\u00e3o do equil\u00edbrio oxidante-antioxidante em beb\u00eas prematuros que s\u00e3o expostos a alto estresse oxidativo induzido principalmente por suplementa\u00e7\u00e3o de O2 e NP contaminada com per\u00f3xido (5).<\/p>\n<p>A ciste\u00edna \u00e9 um amino\u00e1cido n\u00e3o essencial em condi\u00e7\u00f5es normais, mas se torna um amino\u00e1cido essencial em circunst\u00e2ncias espec\u00edficas, como prematuridade e sob estresse oxidativo (5).<\/p>\n<p>Em beb\u00eas prematuros, alguns estudos mostraram que a suplementa\u00e7\u00e3o parenteral de ciste\u00edna pode n\u00e3o melhorar o crescimento neonatal nem reduzir doen\u00e7as, devido \u00e0 imaturidade na capta\u00e7\u00e3o celular de ciste\u00edna. Como alternativa, a glutationa oxidada (GSSG) pode atuar como um reservat\u00f3rio de ciste\u00edna (5).<\/p>\n<h5><strong>Taurina<\/strong><\/h5>\n<p>Embora n\u00e3o fa\u00e7a parte de nenhuma prote\u00edna, a taurina \u00e9 amplamente distribu\u00edda no corpo e \u00e9 o amino\u00e1cido livre mais abundante no leite materno humano. Alta concentra\u00e7\u00e3o de taurina \u00e9 encontrada no c\u00e9rebro, retina madura e ouvido interno (6).<\/p>\n<p>Nos tecidos neurais, a taurina funciona como um osm\u00f3lito org\u00e2nico intracelular, regulando assim o volume da c\u00e9lula neural. Ao modular a homeostase do c\u00e1lcio intracelular, tem efeito estabilizador da membrana. A taurina tamb\u00e9m tem efeito citoprotetor contra danos oxidativos e excitotoxicidade induzida por glutamato (6).<\/p>\n<p>Os rec\u00e9m-nascidos prematuros s\u00e3o mais vulner\u00e1veis \u00e0 defici\u00eancia de taurina devido \u00e0 baixa capacidade de s\u00edntese end\u00f3gena e maior perda renal (6).<\/p>\n<p>Assim, segundo a Sociedade Europeia de Nutri\u00e7\u00e3o Cl\u00ednica e Metabolismo (2), apesar de n\u00e3o se tratar de um amino\u00e1cido t\u00edpico, a taurina deve fazer parte das solu\u00e7\u00f5es de amino\u00e1cidos para lactentes e crian\u00e7as em nutri\u00e7\u00e3o parenteral.<\/p>\n<h5><strong>Arginina<\/strong><\/h5>\n<p>L-arginina \u00e9 o amino\u00e1cido mais rico em nitrog\u00eanio, atuando como um precursor essencial para a s\u00edntese de metab\u00f3litos contendo nitrog\u00eanio e um intermedi\u00e1rio essencial na depura\u00e7\u00e3o do excesso de nitrog\u00eanio. Suas propriedades incluem um papel prim\u00e1rio na excre\u00e7\u00e3o de nitrog\u00eanio, sinaliza\u00e7\u00e3o celular e tamponamento de energia (7).<\/p>\n<p>A suplementa\u00e7\u00e3o de arginina pode ser usada em rec\u00e9m-nascidos prematuros, pois ela contribui para a vasodilata\u00e7\u00e3o e a homeostase da glicose e ajuda a prevenir a enterocolite necrosante. Al\u00e9m disso, a arginina pode estar relacionada \u00e0 imunidade desses beb\u00eas (2, 8).<\/p>\n<p>Em seu consenso sobre o uso de prote\u00edna em pacientes cr\u00edticos, a Associa\u00e7\u00e3o Colombiana de Nutri\u00e7\u00e3o Cl\u00ednica (ACNC) e de Medicina Cr\u00edtica e Terapia Intensiva (AMCI) (10) sugeriu que uso de amino\u00e1cidos suplementares (arginina e seus precursores glutamina e citrulina) \u00e9 indicado quando houver confirma\u00e7\u00e3o de defici\u00eancia. Estes casos incluem, por exemplo:<\/p>\n<ul>\n<li>Paciente submetido a cirurgia eletiva de grande porte (principalmente em cirurgia eletiva para c\u00e2ncer gastrointestinal);<\/li>\n<li>Paciente com anemia de c\u00e9lulas falciformes e crises de anemia hemol\u00edtica;<\/li>\n<li>Paciente submetido a quimioterapia\/radioterapia para c\u00e2ncer de cabe\u00e7a e pesco\u00e7o.\n<p>Al\u00e9m disso, a suplementa\u00e7\u00e3o deste amino\u00e1cido parece promissora nos seguintes casos:<\/li>\n<li>Paciente com trauma m\u00faltiplo;<\/li>\n<li>Paciente com queimaduras (abrangendo mais de 25% da superf\u00edcie corporal total);<\/li>\n<li>Paciente submetido a cirurgia reconstrutiva (com retalhos pediculados ou retalhos revascularizados).<\/li>\n<\/ul>\n<h5><strong>Glutamina<\/strong><\/h5>\n<p>Quando utilizada pela via parenteral, nas concentra\u00e7\u00f5es de 0,3 a 0,5 g\/kg\/ dia e, no m\u00e1ximo, de 30% do nitrog\u00eanio total prescrito, a glutamina reduz a incid\u00eancia de complica\u00e7\u00f5es infecciosas, tempos de interna\u00e7\u00e3o na UTI e no hospital, tempo de ventila\u00e7\u00e3o mec\u00e2nica e taxa de mortalidade hospitalar (11).<\/p>\n<p>Em uma pesquisa que analisou a suplementa\u00e7\u00e3o parenteral com GLN em pacientes cir\u00fargicos cr\u00edticos com base em sete ensaios cl\u00ednicos randomizados (ECRs), as infec\u00e7\u00f5es foram significativamente reduzidas. Al\u00e9m disso, o tempo de interna\u00e7\u00e3o hospitalar foi 4,09 dias menor (12).<\/p>\n<p>Entretanto, o uso parenteral de glutamina est\u00e1 contraindicado em pacientes com disfun\u00e7\u00e3o org\u00e2nica m\u00faltipla, disfun\u00e7\u00e3o renal, disfun\u00e7\u00e3o hep\u00e1tica ou instabilidade hemodin\u00e2mica (13).<\/p>\n<h2><strong>O que podemos concluir?<\/strong><\/h2>\n<p>Em resumo, a utiliza\u00e7\u00e3o de diferentes amino\u00e1cidos na nutri\u00e7\u00e3o parenteral apresenta vantagens significativas para o suporte e recupera\u00e7\u00e3o dos pacientes. A composi\u00e7\u00e3o adequada \u00e9 crucial para manter o equil\u00edbrio energ\u00e9tico e proteico, assegurando a constru\u00e7\u00e3o e manuten\u00e7\u00e3o de tecidos, a s\u00edntese de horm\u00f4nios e enzimas, al\u00e9m de contribuir para a resposta imunol\u00f3gica e a homeostase metab\u00f3lica.<\/p>\n<p>Cada amino\u00e1cido exerce fun\u00e7\u00f5es espec\u00edficas que podem ser adaptadas conforme as necessidades cl\u00ednicas individuais, proporcionando suporte anab\u00f3lico, prote\u00e7\u00e3o antioxidante, controle do catabolismo e reparo tecidual.<\/p>\n<p>Assim, a nutri\u00e7\u00e3o parenteral bem formulada torna-se uma ferramenta indispens\u00e1vel para minimizar complica\u00e7\u00f5es, promover a recupera\u00e7\u00e3o e melhorar os desfechos cl\u00ednicos, especialmente em contextos de estado cr\u00edtico e necessidades nutricionais elevadas.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Refer\u00eancias<\/p>\n<ol>\n<li>Iacone R, Scanzano C, Santarpia L, Cioffi I, Contaldo F, Pasanisi F. Macronutrients in parenteral nutrition: amino acids. Nutrients. 2020;12(3):772.<\/li>\n<li>van Goudoever JB, et al. ESPGHAN\/ESPEN\/ESPR guidelines on pediatric parenteral nutrition: Amino acids. European Society for Clinical Nutrition and Metabolism. 2018.<\/li>\n<li>Hoffer LJ. Parenteral Nutrition: Amino Acids. Nutrients. 2017;9(3):257.<\/li>\n<li>Yarandi SS, Zhao VM, Hebbar G, Ziegler TR. Amino Acid Composition in Parenteral Nutrition: What is the Evidence? Curr Opin Clin Nutr Metab Care. 2011;14(1):75-82.<\/li>\n<li>Mohamed I, El Raichani N, Otis AS, Lavoie JC. Parenteral Cysteine Supplementation in Preterm Infants: One Size Does Not Fit All. Biomedicines. 2023 Dec 27;12(1):63.<\/li>\n<li>Chawla D. Taurine and Neonatal Nutrition. Indian J Pediatr. 2018;85(10):829.<\/li>\n<li>Fung TS, Ryu KW, Thompson CB. Arginine: at the crossroads of nitrogen metabolism. EMBO J. 2025 Mar;44(5):1275-1293.<\/li>\n<li>Badurdeen S, Mulongo M, Berkley JA. Arginine depletion increases susceptibility to serious infections in preterm newborns. Pediatr Res. 2015;77(2):290-297..<\/li>\n<li>Trejos-Gallego D, Peternina FP, Cano AP, Barbosa JB, Gautier JBO, Waitzberg D, Ricardo VCN. Consenso sobre el uso de prote\u00edna en el paciente cr\u00edtico\u2013ACNC. Revista de Nutrici\u00f3n Cl\u00ednica y Metabolismo. 2023;6(2):11-34.<\/li>\n<li>Stehle P, Ellger B, Kojic D, Feuersenger A, Schneid C, Stover J, et al. Glutamine dipeptide-supplemented parenteral nutrition improves the clinical outcomes of critically ill patients: a systematic evaluation of randomised controlled trials. Clin Nutr ESPEN. 2017;17:75-85.<\/li>\n<li>Pimentel RFW, Fernandes SL. Effects of parenteral glutamine in critically ill surgical patients: a systematic review and meta-analysis. Nutr Hosp. 2020 Jul 13;34(3):616-621.<\/li>\n<li>Castro MG, et al. Diretriz Brasileira de Terapia Nutricional no Paciente Grave. BRASPEN J. 2018;33(Supl 1):2-36.<\/li>\n<\/ol>\n","protected":false},"excerpt":{"rendered":"<p>O fornecimento de amino\u00e1cidos na nutri\u00e7\u00e3o parenteral \u00e9 um dos fatores mais importantes no suporte nutricional. Nesse sentido, existem diversos tipos de amino\u00e1cidos, que exercem fun\u00e7\u00f5es espec\u00edficas no organismo. A seguir, vamos entender como eles se dividem e como podem ser usados para as diferentes necessidades dos pacientes que precisam de nutri\u00e7\u00e3o parenteral. Papel dos [&hellip;]<\/p>\n","protected":false},"author":67,"featured_media":2094,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[49],"tags":[94,307,310,308,141,306,67,146,243,309,143],"class_list":["post-1816","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-artigo-5","tag-aminoacidos","tag-arginina","tag-balanco-nitrogenado","tag-cisteina","tag-glutamina","tag-leucina","tag-nutricao-parenteral","tag-pacientes-criticos","tag-suporte-nutricional","tag-taurina","tag-terapia-nutricional"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vantagens no uso de amino\u00e1cidos na nutri\u00e7\u00e3o parenteral<\/title>\n<meta name=\"description\" content=\"Entenda os benef\u00edcios e atua\u00e7\u00e3o do uso de amino\u00e1cidos na nutri\u00e7\u00e3o parenteral e saiba a fun\u00e7\u00e3o de cada um deles.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lam.unitedforclinicalnutrition.com\/pt-br\/diferentes-aminoacidos-nutricao-parenteral\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vantagens no uso de amino\u00e1cidos na nutri\u00e7\u00e3o parenteral\" \/>\n<meta property=\"og:description\" content=\"Entenda os benef\u00edcios e atua\u00e7\u00e3o do uso de amino\u00e1cidos na nutri\u00e7\u00e3o parenteral e saiba a fun\u00e7\u00e3o de cada um deles.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lam.unitedforclinicalnutrition.com\/pt-br\/diferentes-aminoacidos-nutricao-parenteral\/\" \/>\n<meta property=\"og:site_name\" content=\"Unidos pela Nutri\u00e7\u00e3o Cl\u00ednica | Brasil\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-20T13:38:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-20T15:14:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lam.unitedforclinicalnutrition.com\/pt-br\/wp-content\/uploads\/sites\/3\/2022\/08\/lam-198-ban-1024x683px.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"danielle.rolim_130\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"danielle.rolim_130\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/pt-br\\\/diferentes-aminoacidos-nutricao-parenteral\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/pt-br\\\/diferentes-aminoacidos-nutricao-parenteral\\\/\"},\"author\":{\"name\":\"danielle.rolim_130\",\"@id\":\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/pt-br\\\/#\\\/schema\\\/person\\\/c45dfa32ad9e468917e46a308562e8f0\"},\"headline\":\"Vantagens no uso de diferentes amino\u00e1cidos na nutri\u00e7\u00e3o parenteral\",\"datePublished\":\"2025-08-20T13:38:15+00:00\",\"dateModified\":\"2025-08-20T15:14:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/pt-br\\\/diferentes-aminoacidos-nutricao-parenteral\\\/\"},\"wordCount\":1782,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/pt-br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/pt-br\\\/diferentes-aminoacidos-nutricao-parenteral\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/pt-br\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/08\\\/lam-198-ban-1024x683px.png\",\"keywords\":[\"amino\u00e1cidos\",\"arginina\",\"balan\u00e7o nitrogenado\",\"ciste\u00edna\",\"glutamina\",\"leucina\",\"nutri\u00e7\u00e3o parenteral\",\"pacientes cr\u00edticos\",\"suporte nutricional\",\"taurina\",\"terapia nutricional\"],\"articleSection\":[\"Artigos\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/pt-br\\\/diferentes-aminoacidos-nutricao-parenteral\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/pt-br\\\/diferentes-aminoacidos-nutricao-parenteral\\\/\",\"url\":\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/pt-br\\\/diferentes-aminoacidos-nutricao-parenteral\\\/\",\"name\":\"Vantagens no uso de amino\u00e1cidos na nutri\u00e7\u00e3o parenteral\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/pt-br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/pt-br\\\/diferentes-aminoacidos-nutricao-parenteral\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/pt-br\\\/diferentes-aminoacidos-nutricao-parenteral\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/pt-br\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/08\\\/lam-198-ban-1024x683px.png\",\"datePublished\":\"2025-08-20T13:38:15+00:00\",\"dateModified\":\"2025-08-20T15:14:59+00:00\",\"description\":\"Entenda os benef\u00edcios e atua\u00e7\u00e3o do uso de amino\u00e1cidos na nutri\u00e7\u00e3o parenteral e saiba a fun\u00e7\u00e3o de cada um deles.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/pt-br\\\/diferentes-aminoacidos-nutricao-parenteral\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/pt-br\\\/diferentes-aminoacidos-nutricao-parenteral\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/pt-br\\\/diferentes-aminoacidos-nutricao-parenteral\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/pt-br\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/08\\\/lam-198-ban-1024x683px.png\",\"contentUrl\":\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/pt-br\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/08\\\/lam-198-ban-1024x683px.png\",\"width\":1024,\"height\":683},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/pt-br\\\/diferentes-aminoacidos-nutricao-parenteral\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/pt-br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vantagens no uso de diferentes amino\u00e1cidos na nutri\u00e7\u00e3o parenteral\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/pt-br\\\/#website\",\"url\":\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/pt-br\\\/\",\"name\":\"Unidos pela Nutri\u00e7\u00e3o Cl\u00ednica | Brasil\",\"description\":\"\u00c9 uma iniciativa criada pela Fresenius Kabi para ajudar aos profissionais de sa\u00fade.\",\"publisher\":{\"@id\":\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/pt-br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/pt-br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/pt-br\\\/#organization\",\"name\":\"Fresenius Kabi AG\",\"url\":\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/pt-br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/pt-br\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2018\\\/06\\\/Downloads_en_0001_Logo_edit_portugues.jpg\",\"contentUrl\":\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/pt-br\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2018\\\/06\\\/Downloads_en_0001_Logo_edit_portugues.jpg\",\"width\":600,\"height\":400,\"caption\":\"Fresenius Kabi AG\"},\"image\":{\"@id\":\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/pt-br\\\/#\\\/schema\\\/person\\\/c45dfa32ad9e468917e46a308562e8f0\",\"name\":\"danielle.rolim_130\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/72a8f8d00ec59d00659931da34e36d0ba579e9b190fa8aac86e5e7603be9f229?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/72a8f8d00ec59d00659931da34e36d0ba579e9b190fa8aac86e5e7603be9f229?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/72a8f8d00ec59d00659931da34e36d0ba579e9b190fa8aac86e5e7603be9f229?s=96&d=mm&r=g\",\"caption\":\"danielle.rolim_130\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vantagens no uso de amino\u00e1cidos na nutri\u00e7\u00e3o parenteral","description":"Entenda os benef\u00edcios e atua\u00e7\u00e3o do uso de amino\u00e1cidos na nutri\u00e7\u00e3o parenteral e saiba a fun\u00e7\u00e3o de cada um deles.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lam.unitedforclinicalnutrition.com\/pt-br\/diferentes-aminoacidos-nutricao-parenteral\/","og_locale":"pt_BR","og_type":"article","og_title":"Vantagens no uso de amino\u00e1cidos na nutri\u00e7\u00e3o parenteral","og_description":"Entenda os benef\u00edcios e atua\u00e7\u00e3o do uso de amino\u00e1cidos na nutri\u00e7\u00e3o parenteral e saiba a fun\u00e7\u00e3o de cada um deles.","og_url":"https:\/\/lam.unitedforclinicalnutrition.com\/pt-br\/diferentes-aminoacidos-nutricao-parenteral\/","og_site_name":"Unidos pela Nutri\u00e7\u00e3o Cl\u00ednica | Brasil","article_published_time":"2025-08-20T13:38:15+00:00","article_modified_time":"2025-08-20T15:14:59+00:00","og_image":[{"width":1024,"height":683,"url":"https:\/\/lam.unitedforclinicalnutrition.com\/pt-br\/wp-content\/uploads\/sites\/3\/2022\/08\/lam-198-ban-1024x683px.png","type":"image\/png"}],"author":"danielle.rolim_130","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"danielle.rolim_130","Est. tempo de leitura":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lam.unitedforclinicalnutrition.com\/pt-br\/diferentes-aminoacidos-nutricao-parenteral\/#article","isPartOf":{"@id":"https:\/\/lam.unitedforclinicalnutrition.com\/pt-br\/diferentes-aminoacidos-nutricao-parenteral\/"},"author":{"name":"danielle.rolim_130","@id":"https:\/\/lam.unitedforclinicalnutrition.com\/pt-br\/#\/schema\/person\/c45dfa32ad9e468917e46a308562e8f0"},"headline":"Vantagens no uso de diferentes amino\u00e1cidos na nutri\u00e7\u00e3o parenteral","datePublished":"2025-08-20T13:38:15+00:00","dateModified":"2025-08-20T15:14:59+00:00","mainEntityOfPage":{"@id":"https:\/\/lam.unitedforclinicalnutrition.com\/pt-br\/diferentes-aminoacidos-nutricao-parenteral\/"},"wordCount":1782,"commentCount":0,"publisher":{"@id":"https:\/\/lam.unitedforclinicalnutrition.com\/pt-br\/#organization"},"image":{"@id":"https:\/\/lam.unitedforclinicalnutrition.com\/pt-br\/diferentes-aminoacidos-nutricao-parenteral\/#primaryimage"},"thumbnailUrl":"https:\/\/lam.unitedforclinicalnutrition.com\/pt-br\/wp-content\/uploads\/sites\/3\/2022\/08\/lam-198-ban-1024x683px.png","keywords":["amino\u00e1cidos","arginina","balan\u00e7o nitrogenado","ciste\u00edna","glutamina","leucina","nutri\u00e7\u00e3o parenteral","pacientes cr\u00edticos","suporte nutricional","taurina","terapia nutricional"],"articleSection":["Artigos"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/lam.unitedforclinicalnutrition.com\/pt-br\/diferentes-aminoacidos-nutricao-parenteral\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/lam.unitedforclinicalnutrition.com\/pt-br\/diferentes-aminoacidos-nutricao-parenteral\/","url":"https:\/\/lam.unitedforclinicalnutrition.com\/pt-br\/diferentes-aminoacidos-nutricao-parenteral\/","name":"Vantagens no uso de amino\u00e1cidos na nutri\u00e7\u00e3o parenteral","isPartOf":{"@id":"https:\/\/lam.unitedforclinicalnutrition.com\/pt-br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lam.unitedforclinicalnutrition.com\/pt-br\/diferentes-aminoacidos-nutricao-parenteral\/#primaryimage"},"image":{"@id":"https:\/\/lam.unitedforclinicalnutrition.com\/pt-br\/diferentes-aminoacidos-nutricao-parenteral\/#primaryimage"},"thumbnailUrl":"https:\/\/lam.unitedforclinicalnutrition.com\/pt-br\/wp-content\/uploads\/sites\/3\/2022\/08\/lam-198-ban-1024x683px.png","datePublished":"2025-08-20T13:38:15+00:00","dateModified":"2025-08-20T15:14:59+00:00","description":"Entenda os benef\u00edcios e atua\u00e7\u00e3o do uso de amino\u00e1cidos na nutri\u00e7\u00e3o parenteral e saiba a fun\u00e7\u00e3o de cada um deles.","breadcrumb":{"@id":"https:\/\/lam.unitedforclinicalnutrition.com\/pt-br\/diferentes-aminoacidos-nutricao-parenteral\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lam.unitedforclinicalnutrition.com\/pt-br\/diferentes-aminoacidos-nutricao-parenteral\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/lam.unitedforclinicalnutrition.com\/pt-br\/diferentes-aminoacidos-nutricao-parenteral\/#primaryimage","url":"https:\/\/lam.unitedforclinicalnutrition.com\/pt-br\/wp-content\/uploads\/sites\/3\/2022\/08\/lam-198-ban-1024x683px.png","contentUrl":"https:\/\/lam.unitedforclinicalnutrition.com\/pt-br\/wp-content\/uploads\/sites\/3\/2022\/08\/lam-198-ban-1024x683px.png","width":1024,"height":683},{"@type":"BreadcrumbList","@id":"https:\/\/lam.unitedforclinicalnutrition.com\/pt-br\/diferentes-aminoacidos-nutricao-parenteral\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/lam.unitedforclinicalnutrition.com\/pt-br\/"},{"@type":"ListItem","position":2,"name":"Vantagens no uso de diferentes amino\u00e1cidos na nutri\u00e7\u00e3o parenteral"}]},{"@type":"WebSite","@id":"https:\/\/lam.unitedforclinicalnutrition.com\/pt-br\/#website","url":"https:\/\/lam.unitedforclinicalnutrition.com\/pt-br\/","name":"Unidos pela Nutri\u00e7\u00e3o Cl\u00ednica | Brasil","description":"\u00c9 uma iniciativa criada pela Fresenius Kabi para ajudar aos profissionais de sa\u00fade.","publisher":{"@id":"https:\/\/lam.unitedforclinicalnutrition.com\/pt-br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lam.unitedforclinicalnutrition.com\/pt-br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/lam.unitedforclinicalnutrition.com\/pt-br\/#organization","name":"Fresenius Kabi AG","url":"https:\/\/lam.unitedforclinicalnutrition.com\/pt-br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/lam.unitedforclinicalnutrition.com\/pt-br\/#\/schema\/logo\/image\/","url":"https:\/\/lam.unitedforclinicalnutrition.com\/pt-br\/wp-content\/uploads\/sites\/3\/2018\/06\/Downloads_en_0001_Logo_edit_portugues.jpg","contentUrl":"https:\/\/lam.unitedforclinicalnutrition.com\/pt-br\/wp-content\/uploads\/sites\/3\/2018\/06\/Downloads_en_0001_Logo_edit_portugues.jpg","width":600,"height":400,"caption":"Fresenius Kabi AG"},"image":{"@id":"https:\/\/lam.unitedforclinicalnutrition.com\/pt-br\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/lam.unitedforclinicalnutrition.com\/pt-br\/#\/schema\/person\/c45dfa32ad9e468917e46a308562e8f0","name":"danielle.rolim_130","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/72a8f8d00ec59d00659931da34e36d0ba579e9b190fa8aac86e5e7603be9f229?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/72a8f8d00ec59d00659931da34e36d0ba579e9b190fa8aac86e5e7603be9f229?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/72a8f8d00ec59d00659931da34e36d0ba579e9b190fa8aac86e5e7603be9f229?s=96&d=mm&r=g","caption":"danielle.rolim_130"}}]}},"_links":{"self":[{"href":"https:\/\/lam.unitedforclinicalnutrition.com\/pt-br\/wp-json\/wp\/v2\/posts\/1816","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lam.unitedforclinicalnutrition.com\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lam.unitedforclinicalnutrition.com\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lam.unitedforclinicalnutrition.com\/pt-br\/wp-json\/wp\/v2\/users\/67"}],"replies":[{"embeddable":true,"href":"https:\/\/lam.unitedforclinicalnutrition.com\/pt-br\/wp-json\/wp\/v2\/comments?post=1816"}],"version-history":[{"count":0,"href":"https:\/\/lam.unitedforclinicalnutrition.com\/pt-br\/wp-json\/wp\/v2\/posts\/1816\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lam.unitedforclinicalnutrition.com\/pt-br\/wp-json\/wp\/v2\/media\/2094"}],"wp:attachment":[{"href":"https:\/\/lam.unitedforclinicalnutrition.com\/pt-br\/wp-json\/wp\/v2\/media?parent=1816"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lam.unitedforclinicalnutrition.com\/pt-br\/wp-json\/wp\/v2\/categories?post=1816"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lam.unitedforclinicalnutrition.com\/pt-br\/wp-json\/wp\/v2\/tags?post=1816"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}