{"id":1664,"date":"2019-12-26T22:56:15","date_gmt":"2019-12-26T22:56:15","guid":{"rendered":"https:\/\/lam.unitedforclinicalnutrition.com\/es-pe\/?p=1664"},"modified":"2020-03-13T23:06:55","modified_gmt":"2020-03-13T23:06:55","slug":"nutricion-parenteral-enriquecida-con-acido-graso-omega-3-mejora-los-resultados-del-paciente","status":"publish","type":"post","link":"https:\/\/lam.unitedforclinicalnutrition.com\/es-pe\/nutricion-parenteral-enriquecida-con-acido-graso-omega-3-mejora-los-resultados-del-paciente\/","title":{"rendered":"NUTRICION PARENTERAL ENRIQUECIDA CON ACIDO GRASO OMEGA 3 MEJORA LOS RESULTADOS DEL PACIENTE"},"content":{"rendered":"<p>Noviembre 08, 2019<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"alignnone\" src=\"https:\/\/previews.123rf.com\/images\/krasy\/krasy1409\/krasy140900006\/32049136-s%C3%ADmbolo-de-%C3%A1cidos-grasos-omega-3.jpg\" alt=\"Resultado de imagen para omega 3\" \/><\/p>\n<p style=\"text-align: justify;\">BAD HOMBURG, ALEMANIA\u2013 Una revisi\u00f3n sistem\u00e1tica de la literatura y meta-an\u00e1lisis <a class=\"bibliography-sup\" title=\"Pradelli L, Mayer K, Klek S et al. \u03c9-3 Fatty-Acid Enriched Parenteral Nutrition in Hospitalized Patients: Systematic Review With Meta-Analysis and Trial Sequential Analysis. JPEN J Parenter Enteral Nutr. 2019.\" href=\"#\" data-bibliography-link=\"\">1<\/a> confirma y extiende los resultados previos que la nutrici\u00f3n parenteral enriquecida con \u00e1cido graso omega 3 mejora los resultados cl\u00ednicos comparados con nutrici\u00f3n parenteral est\u00e1ndar en pacientes adultos. Un total de 49 ensayos controlados aleatorios fueron incluidos, esta revisi\u00f3n provee el m\u00e1s extenso y actualizado an\u00e1lisis de nutrici\u00f3n parenteral enriquecida con omega 3 en los resultados del paciente.<\/p>\n<p style=\"text-align: justify;\">De acuerdo con este an\u00e1lisis, adicionar \u00e1cidos grasos omega 3 a la nutrici\u00f3n parenteral reduce la estancia en UCI y hospitalaria en dos d\u00edas y el riesgo de infecciones en un 40% comparados con una nutrici\u00f3n parenteral est\u00e1ndar. Adem\u00e1s, el an\u00e1lisis revela que la nutrici\u00f3n parenteral enriquecida con aceite de pescado reduce significativamente el cuadro de sepsis en un 56%. Un an\u00e1lisis del reporte de los par\u00e1metros de laboratorio de los ensayos sugiere que la nutrici\u00f3n parenteral enriquecida con \u00e1cidos grasos omega 3 puede tener un efecto beneficioso en los par\u00e1metros hep\u00e1ticos, niveles de antioxidantes, marcadores de inflamaci\u00f3n y perfil de \u00e1cidos grasos.<\/p>\n<p style=\"text-align: justify;\">Los autores concluyen que deber\u00edan preferirse las emulsiones lip\u00eddicas enriquecidas con \u00e1cidos grasos omega 3 en vez de emulsiones lip\u00eddicas est\u00e1ndar para pacientes que requieren nutrici\u00f3n parenteral.<\/p>\n<p style=\"text-align: justify;\"><strong>Acerca de la revisi\u00f3n y el meta-an\u00e1lisis:<\/strong><\/p>\n<p style=\"text-align: justify;\">El meta-an\u00e1lisis por Lorenzo Pradelli y colegas fue publicado en el Journal de Nutrici\u00f3n Enteral y Parenteral en Junio 2019. La revisi\u00f3n incluye un total de 49 ensayos controlados aleatorios con resultados de 3641 pacientes adultos hospitalizados divididos en grupos recibiendo emulsi\u00f3n lip\u00eddica enriquecida con \u00e1cidos grasos omega 3 o emulsi\u00f3n lip\u00eddica est\u00e1ndar como parte de su r\u00e9gimen de nutrici\u00f3n parenteral.<\/p>\n<p style=\"text-align: justify;\">S\u00f3lo se incluyeron ensayos controlados aleatorios donde la nutrici\u00f3n parenteral represent\u00f3, como m\u00ednimo, el 70% de la provisi\u00f3n de energ\u00eda diaria.<\/p>\n<p style=\"text-align: justify;\">Para mis informaci\u00f3n puedes encontrar la publicaci\u00f3n en el siguiente link.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/onlinelibrary.wiley.com\/doi\/full\/10.1002\/jpen.1672\">https:\/\/onlinelibrary.wiley.com\/doi\/full\/10.1002\/jpen.1672<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Noviembre 08, 2019 &nbsp; BAD HOMBURG, ALEMANIA\u2013 Una revisi\u00f3n sistem\u00e1tica de la literatura y meta-an\u00e1lisis 1 confirma y extiende los resultados previos que la nutrici\u00f3n parenteral enriquecida con \u00e1cido graso omega 3 mejora los resultados cl\u00ednicos comparados con nutrici\u00f3n parenteral est\u00e1ndar en pacientes adultos. Un total de 49 ensayos controlados aleatorios fueron incluidos, esta revisi\u00f3n [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":1665,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[59,14],"tags":[],"class_list":["post-1664","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-articulo-4","category-nutricion-parenteral"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>NUTRICION PARENTERAL ENRIQUECIDA CON ACIDO GRASO OMEGA 3 MEJORA LOS RESULTADOS DEL PACIENTE - Unidos por la Nutrici\u00f3n Cl\u00ednica | Per\u00fa<\/title>\n<meta name=\"description\" content=\"Noviembre 08, 2019 &nbsp; BAD HOMBURG, ALEMANIA\u2013 Una revisi\u00f3n sistem\u00e1tica de la literatura y meta-an\u00e1lisis 1 confirma y extiende los resultados previos\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lam.unitedforclinicalnutrition.com\/es-pe\/nutricion-parenteral-enriquecida-con-acido-graso-omega-3-mejora-los-resultados-del-paciente\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"NUTRICION PARENTERAL ENRIQUECIDA CON ACIDO GRASO OMEGA 3 MEJORA LOS RESULTADOS DEL PACIENTE - Unidos por la Nutrici\u00f3n Cl\u00ednica | Per\u00fa\" \/>\n<meta property=\"og:description\" content=\"Noviembre 08, 2019 &nbsp; BAD HOMBURG, ALEMANIA\u2013 Una revisi\u00f3n sistem\u00e1tica de la literatura y meta-an\u00e1lisis 1 confirma y extiende los resultados previos\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lam.unitedforclinicalnutrition.com\/es-pe\/nutricion-parenteral-enriquecida-con-acido-graso-omega-3-mejora-los-resultados-del-paciente\/\" \/>\n<meta property=\"og:site_name\" content=\"Unidos por la Nutrici\u00f3n Cl\u00ednica | Per\u00fa\" \/>\n<meta property=\"article:published_time\" content=\"2019-12-26T22:56:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-03-13T23:06:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lam.unitedforclinicalnutrition.com\/es-pe\/wp-content\/uploads\/sites\/8\/2019\/12\/istockphoto-453531293-1024x1024.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ceciliatorres\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"ceciliatorres\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/es-pe\\\/nutricion-parenteral-enriquecida-con-acido-graso-omega-3-mejora-los-resultados-del-paciente\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/es-pe\\\/nutricion-parenteral-enriquecida-con-acido-graso-omega-3-mejora-los-resultados-del-paciente\\\/\"},\"author\":{\"name\":\"ceciliatorres\",\"@id\":\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/es-pe\\\/#\\\/schema\\\/person\\\/f327d4e887aae8ed5ee5203e220af768\"},\"headline\":\"NUTRICION PARENTERAL ENRIQUECIDA CON ACIDO GRASO OMEGA 3 MEJORA LOS RESULTADOS DEL PACIENTE\",\"datePublished\":\"2019-12-26T22:56:15+00:00\",\"dateModified\":\"2020-03-13T23:06:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/es-pe\\\/nutricion-parenteral-enriquecida-con-acido-graso-omega-3-mejora-los-resultados-del-paciente\\\/\"},\"wordCount\":356,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/es-pe\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/es-pe\\\/nutricion-parenteral-enriquecida-con-acido-graso-omega-3-mejora-los-resultados-del-paciente\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/es-pe\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2019\\\/12\\\/istockphoto-453531293-1024x1024.jpg\",\"articleSection\":[\"Art\u00edculos\",\"Nutrici\u00f3n Parenteral\"],\"inLanguage\":\"es-PE\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/es-pe\\\/nutricion-parenteral-enriquecida-con-acido-graso-omega-3-mejora-los-resultados-del-paciente\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/es-pe\\\/nutricion-parenteral-enriquecida-con-acido-graso-omega-3-mejora-los-resultados-del-paciente\\\/\",\"url\":\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/es-pe\\\/nutricion-parenteral-enriquecida-con-acido-graso-omega-3-mejora-los-resultados-del-paciente\\\/\",\"name\":\"NUTRICION PARENTERAL ENRIQUECIDA CON ACIDO GRASO OMEGA 3 MEJORA LOS RESULTADOS DEL PACIENTE - Unidos por la Nutrici\u00f3n Cl\u00ednica | Per\u00fa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/es-pe\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/es-pe\\\/nutricion-parenteral-enriquecida-con-acido-graso-omega-3-mejora-los-resultados-del-paciente\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/es-pe\\\/nutricion-parenteral-enriquecida-con-acido-graso-omega-3-mejora-los-resultados-del-paciente\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/es-pe\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2019\\\/12\\\/istockphoto-453531293-1024x1024.jpg\",\"datePublished\":\"2019-12-26T22:56:15+00:00\",\"dateModified\":\"2020-03-13T23:06:55+00:00\",\"description\":\"Noviembre 08, 2019 &nbsp; BAD HOMBURG, ALEMANIA\u2013 Una revisi\u00f3n sistem\u00e1tica de la literatura y meta-an\u00e1lisis 1 confirma y extiende los resultados previos\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/es-pe\\\/nutricion-parenteral-enriquecida-con-acido-graso-omega-3-mejora-los-resultados-del-paciente\\\/#breadcrumb\"},\"inLanguage\":\"es-PE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/es-pe\\\/nutricion-parenteral-enriquecida-con-acido-graso-omega-3-mejora-los-resultados-del-paciente\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-PE\",\"@id\":\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/es-pe\\\/nutricion-parenteral-enriquecida-con-acido-graso-omega-3-mejora-los-resultados-del-paciente\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/es-pe\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2019\\\/12\\\/istockphoto-453531293-1024x1024.jpg\",\"contentUrl\":\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/es-pe\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2019\\\/12\\\/istockphoto-453531293-1024x1024.jpg\",\"width\":1024,\"height\":683,\"caption\":\"omega 3 on white background\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/es-pe\\\/nutricion-parenteral-enriquecida-con-acido-graso-omega-3-mejora-los-resultados-del-paciente\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/es-pe\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"NUTRICION PARENTERAL ENRIQUECIDA CON ACIDO GRASO OMEGA 3 MEJORA LOS RESULTADOS DEL PACIENTE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/es-pe\\\/#website\",\"url\":\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/es-pe\\\/\",\"name\":\"Unidos por la Nutrici\u00f3n Cl\u00ednica | Per\u00fa\",\"description\":\"Es una iniciativa creada por Fresenius Kabi para trabajar en conjunto con los profesionales de la salud.\",\"publisher\":{\"@id\":\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/es-pe\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/es-pe\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-PE\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/es-pe\\\/#organization\",\"name\":\"Fresenius Kabi AG\",\"url\":\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/es-pe\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-PE\",\"@id\":\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/es-pe\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/es-pe\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/revslider\\\/home_slider\\\/Logo_edit_english.png\",\"contentUrl\":\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/es-pe\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/revslider\\\/home_slider\\\/Logo_edit_english.png\",\"width\":914,\"height\":807,\"caption\":\"Fresenius Kabi AG\"},\"image\":{\"@id\":\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/es-pe\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/es-pe\\\/#\\\/schema\\\/person\\\/f327d4e887aae8ed5ee5203e220af768\",\"name\":\"ceciliatorres\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-PE\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1fe20698fe3e4eb31457cc3c6a7294cf5a200355f1563495f0ccb3d5aa0576bd?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1fe20698fe3e4eb31457cc3c6a7294cf5a200355f1563495f0ccb3d5aa0576bd?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1fe20698fe3e4eb31457cc3c6a7294cf5a200355f1563495f0ccb3d5aa0576bd?s=96&d=mm&r=g\",\"caption\":\"ceciliatorres\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"NUTRICION PARENTERAL ENRIQUECIDA CON ACIDO GRASO OMEGA 3 MEJORA LOS RESULTADOS DEL PACIENTE - Unidos por la Nutrici\u00f3n Cl\u00ednica | Per\u00fa","description":"Noviembre 08, 2019 &nbsp; BAD HOMBURG, ALEMANIA\u2013 Una revisi\u00f3n sistem\u00e1tica de la literatura y meta-an\u00e1lisis 1 confirma y extiende los resultados previos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lam.unitedforclinicalnutrition.com\/es-pe\/nutricion-parenteral-enriquecida-con-acido-graso-omega-3-mejora-los-resultados-del-paciente\/","og_locale":"es_ES","og_type":"article","og_title":"NUTRICION PARENTERAL ENRIQUECIDA CON ACIDO GRASO OMEGA 3 MEJORA LOS RESULTADOS DEL PACIENTE - Unidos por la Nutrici\u00f3n Cl\u00ednica | Per\u00fa","og_description":"Noviembre 08, 2019 &nbsp; BAD HOMBURG, ALEMANIA\u2013 Una revisi\u00f3n sistem\u00e1tica de la literatura y meta-an\u00e1lisis 1 confirma y extiende los resultados previos","og_url":"https:\/\/lam.unitedforclinicalnutrition.com\/es-pe\/nutricion-parenteral-enriquecida-con-acido-graso-omega-3-mejora-los-resultados-del-paciente\/","og_site_name":"Unidos por la Nutrici\u00f3n Cl\u00ednica | Per\u00fa","article_published_time":"2019-12-26T22:56:15+00:00","article_modified_time":"2020-03-13T23:06:55+00:00","og_image":[{"width":1024,"height":683,"url":"https:\/\/lam.unitedforclinicalnutrition.com\/es-pe\/wp-content\/uploads\/sites\/8\/2019\/12\/istockphoto-453531293-1024x1024.jpg","type":"image\/jpeg"}],"author":"ceciliatorres","twitter_card":"summary_large_image","twitter_misc":{"Written by":"ceciliatorres","Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lam.unitedforclinicalnutrition.com\/es-pe\/nutricion-parenteral-enriquecida-con-acido-graso-omega-3-mejora-los-resultados-del-paciente\/#article","isPartOf":{"@id":"https:\/\/lam.unitedforclinicalnutrition.com\/es-pe\/nutricion-parenteral-enriquecida-con-acido-graso-omega-3-mejora-los-resultados-del-paciente\/"},"author":{"name":"ceciliatorres","@id":"https:\/\/lam.unitedforclinicalnutrition.com\/es-pe\/#\/schema\/person\/f327d4e887aae8ed5ee5203e220af768"},"headline":"NUTRICION PARENTERAL ENRIQUECIDA CON ACIDO GRASO OMEGA 3 MEJORA LOS RESULTADOS DEL PACIENTE","datePublished":"2019-12-26T22:56:15+00:00","dateModified":"2020-03-13T23:06:55+00:00","mainEntityOfPage":{"@id":"https:\/\/lam.unitedforclinicalnutrition.com\/es-pe\/nutricion-parenteral-enriquecida-con-acido-graso-omega-3-mejora-los-resultados-del-paciente\/"},"wordCount":356,"commentCount":0,"publisher":{"@id":"https:\/\/lam.unitedforclinicalnutrition.com\/es-pe\/#organization"},"image":{"@id":"https:\/\/lam.unitedforclinicalnutrition.com\/es-pe\/nutricion-parenteral-enriquecida-con-acido-graso-omega-3-mejora-los-resultados-del-paciente\/#primaryimage"},"thumbnailUrl":"https:\/\/lam.unitedforclinicalnutrition.com\/es-pe\/wp-content\/uploads\/sites\/8\/2019\/12\/istockphoto-453531293-1024x1024.jpg","articleSection":["Art\u00edculos","Nutrici\u00f3n Parenteral"],"inLanguage":"es-PE","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/lam.unitedforclinicalnutrition.com\/es-pe\/nutricion-parenteral-enriquecida-con-acido-graso-omega-3-mejora-los-resultados-del-paciente\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/lam.unitedforclinicalnutrition.com\/es-pe\/nutricion-parenteral-enriquecida-con-acido-graso-omega-3-mejora-los-resultados-del-paciente\/","url":"https:\/\/lam.unitedforclinicalnutrition.com\/es-pe\/nutricion-parenteral-enriquecida-con-acido-graso-omega-3-mejora-los-resultados-del-paciente\/","name":"NUTRICION PARENTERAL ENRIQUECIDA CON ACIDO GRASO OMEGA 3 MEJORA LOS RESULTADOS DEL PACIENTE - Unidos por la Nutrici\u00f3n Cl\u00ednica | Per\u00fa","isPartOf":{"@id":"https:\/\/lam.unitedforclinicalnutrition.com\/es-pe\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lam.unitedforclinicalnutrition.com\/es-pe\/nutricion-parenteral-enriquecida-con-acido-graso-omega-3-mejora-los-resultados-del-paciente\/#primaryimage"},"image":{"@id":"https:\/\/lam.unitedforclinicalnutrition.com\/es-pe\/nutricion-parenteral-enriquecida-con-acido-graso-omega-3-mejora-los-resultados-del-paciente\/#primaryimage"},"thumbnailUrl":"https:\/\/lam.unitedforclinicalnutrition.com\/es-pe\/wp-content\/uploads\/sites\/8\/2019\/12\/istockphoto-453531293-1024x1024.jpg","datePublished":"2019-12-26T22:56:15+00:00","dateModified":"2020-03-13T23:06:55+00:00","description":"Noviembre 08, 2019 &nbsp; BAD HOMBURG, ALEMANIA\u2013 Una revisi\u00f3n sistem\u00e1tica de la literatura y meta-an\u00e1lisis 1 confirma y extiende los resultados previos","breadcrumb":{"@id":"https:\/\/lam.unitedforclinicalnutrition.com\/es-pe\/nutricion-parenteral-enriquecida-con-acido-graso-omega-3-mejora-los-resultados-del-paciente\/#breadcrumb"},"inLanguage":"es-PE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lam.unitedforclinicalnutrition.com\/es-pe\/nutricion-parenteral-enriquecida-con-acido-graso-omega-3-mejora-los-resultados-del-paciente\/"]}]},{"@type":"ImageObject","inLanguage":"es-PE","@id":"https:\/\/lam.unitedforclinicalnutrition.com\/es-pe\/nutricion-parenteral-enriquecida-con-acido-graso-omega-3-mejora-los-resultados-del-paciente\/#primaryimage","url":"https:\/\/lam.unitedforclinicalnutrition.com\/es-pe\/wp-content\/uploads\/sites\/8\/2019\/12\/istockphoto-453531293-1024x1024.jpg","contentUrl":"https:\/\/lam.unitedforclinicalnutrition.com\/es-pe\/wp-content\/uploads\/sites\/8\/2019\/12\/istockphoto-453531293-1024x1024.jpg","width":1024,"height":683,"caption":"omega 3 on white background"},{"@type":"BreadcrumbList","@id":"https:\/\/lam.unitedforclinicalnutrition.com\/es-pe\/nutricion-parenteral-enriquecida-con-acido-graso-omega-3-mejora-los-resultados-del-paciente\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/lam.unitedforclinicalnutrition.com\/es-pe\/"},{"@type":"ListItem","position":2,"name":"NUTRICION PARENTERAL ENRIQUECIDA CON ACIDO GRASO OMEGA 3 MEJORA LOS RESULTADOS DEL PACIENTE"}]},{"@type":"WebSite","@id":"https:\/\/lam.unitedforclinicalnutrition.com\/es-pe\/#website","url":"https:\/\/lam.unitedforclinicalnutrition.com\/es-pe\/","name":"Unidos por la Nutrici\u00f3n Cl\u00ednica | Per\u00fa","description":"Es una iniciativa creada por Fresenius Kabi para trabajar en conjunto con los profesionales de la salud.","publisher":{"@id":"https:\/\/lam.unitedforclinicalnutrition.com\/es-pe\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lam.unitedforclinicalnutrition.com\/es-pe\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-PE"},{"@type":"Organization","@id":"https:\/\/lam.unitedforclinicalnutrition.com\/es-pe\/#organization","name":"Fresenius Kabi AG","url":"https:\/\/lam.unitedforclinicalnutrition.com\/es-pe\/","logo":{"@type":"ImageObject","inLanguage":"es-PE","@id":"https:\/\/lam.unitedforclinicalnutrition.com\/es-pe\/#\/schema\/logo\/image\/","url":"https:\/\/lam.unitedforclinicalnutrition.com\/es-pe\/wp-content\/uploads\/sites\/8\/revslider\/home_slider\/Logo_edit_english.png","contentUrl":"https:\/\/lam.unitedforclinicalnutrition.com\/es-pe\/wp-content\/uploads\/sites\/8\/revslider\/home_slider\/Logo_edit_english.png","width":914,"height":807,"caption":"Fresenius Kabi AG"},"image":{"@id":"https:\/\/lam.unitedforclinicalnutrition.com\/es-pe\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/lam.unitedforclinicalnutrition.com\/es-pe\/#\/schema\/person\/f327d4e887aae8ed5ee5203e220af768","name":"ceciliatorres","image":{"@type":"ImageObject","inLanguage":"es-PE","@id":"https:\/\/secure.gravatar.com\/avatar\/1fe20698fe3e4eb31457cc3c6a7294cf5a200355f1563495f0ccb3d5aa0576bd?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1fe20698fe3e4eb31457cc3c6a7294cf5a200355f1563495f0ccb3d5aa0576bd?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1fe20698fe3e4eb31457cc3c6a7294cf5a200355f1563495f0ccb3d5aa0576bd?s=96&d=mm&r=g","caption":"ceciliatorres"}}]}},"_links":{"self":[{"href":"https:\/\/lam.unitedforclinicalnutrition.com\/es-pe\/wp-json\/wp\/v2\/posts\/1664","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lam.unitedforclinicalnutrition.com\/es-pe\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lam.unitedforclinicalnutrition.com\/es-pe\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lam.unitedforclinicalnutrition.com\/es-pe\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/lam.unitedforclinicalnutrition.com\/es-pe\/wp-json\/wp\/v2\/comments?post=1664"}],"version-history":[{"count":0,"href":"https:\/\/lam.unitedforclinicalnutrition.com\/es-pe\/wp-json\/wp\/v2\/posts\/1664\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lam.unitedforclinicalnutrition.com\/es-pe\/wp-json\/wp\/v2\/media\/1665"}],"wp:attachment":[{"href":"https:\/\/lam.unitedforclinicalnutrition.com\/es-pe\/wp-json\/wp\/v2\/media?parent=1664"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lam.unitedforclinicalnutrition.com\/es-pe\/wp-json\/wp\/v2\/categories?post=1664"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lam.unitedforclinicalnutrition.com\/es-pe\/wp-json\/wp\/v2\/tags?post=1664"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}