{"id":449,"date":"2017-05-08T00:00:00","date_gmt":"2017-05-08T00:00:00","guid":{"rendered":"https:\/\/lam.unitedforclinicalnutrition.com\/mx\/conozca-mas-sobre-las-areas-de-mejora-en-un-entorno-hospitalario\/"},"modified":"2020-03-10T23:03:56","modified_gmt":"2020-03-10T23:03:56","slug":"conozca-mas-sobre-las-areas-de-mejora-en-un-entorno-hospitalario","status":"publish","type":"post","link":"https:\/\/lam.unitedforclinicalnutrition.com\/es-mx\/conozca-mas-sobre-las-areas-de-mejora-en-un-entorno-hospitalario\/","title":{"rendered":"Conozca m\u00e1s sobre las \u00e1reas de mejora en un entorno hospitalario"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lam.unitedforclinicalnutrition.com\/es-mx\/wp-content\/uploads\/sites\/5\/2018\/05\/170410_articleeducation_image_carolina.jpg\" alt=\"\" width=\"856\" height=\"386\" class=\"alignnone size-full wp-image-512\" srcset=\"https:\/\/lam.unitedforclinicalnutrition.com\/es-mx\/wp-content\/uploads\/sites\/5\/2018\/05\/170410_articleeducation_image_carolina.jpg 856w, https:\/\/lam.unitedforclinicalnutrition.com\/es-mx\/wp-content\/uploads\/sites\/5\/2018\/05\/170410_articleeducation_image_carolina-300x135.jpg 300w, https:\/\/lam.unitedforclinicalnutrition.com\/es-mx\/wp-content\/uploads\/sites\/5\/2018\/05\/170410_articleeducation_image_carolina-768x346.jpg 768w, https:\/\/lam.unitedforclinicalnutrition.com\/es-mx\/wp-content\/uploads\/sites\/5\/2018\/05\/170410_articleeducation_image_carolina-580x262.jpg 580w\" sizes=\"auto, (max-width: 856px) 100vw, 856px\" \/><\/p>\n<p>Durante el congreso anual de la Sociedad Europea de Nutrici\u00f3n Cl\u00ednica y Metabolismo (ESPEN, seg\u00fan sus siglas en ingl\u00e9s), varios expertos aportaron su opini\u00f3n sobre los cambios fundamentales que se necesitan en los sistemas hospitalarios actuales para implementar la terapia nutricional. Estuvieron de acuerdo en que, para combatir la desnutrici\u00f3n relacionada con enfermedades, tanto la formaci\u00f3n de los profesionales, la capacitaci\u00f3n del personal y el trabajo en equipo, as\u00ed como el hecho de contar con un nutricionista exclusivamente para ese servicio, son todos elementos fundamentales. Algunos de los expertos que compartieron sus opiniones sobre la materia son:<\/p>\n<ul>\n<li>Carolina M\u00e9ndez Mart\u00ednez: nutricionista y dietista de la Universidad Nacional de Colombia.<\/li>\n<li>Dr. Mario Ignacio Perman: intensivista en el Hospital Italiano de Buenos Aires, Argentina.<\/li>\n<li>Dr. Roger Enrique Riofrio: cirujano general de la Universidad Central de Ecuador.<\/li>\n<li>Dr. Alfredo Matos Adames, MD: profesor de nutrici\u00f3n cl\u00ednica y cirug\u00eda en la Facultad de Medicina de la Universidad de Panam\u00e1.<\/li>\n<\/ul>\n<p>El Congreso de ESPEN es una convenci\u00f3n internacional anual que abarca varios temas en el campo de la nutrici\u00f3n parenteral y enteral, y que recientemente reuni\u00f3 a m\u00e1s de 3000 participantes de 82 pa\u00edses diferentes. En septiembre de 2015, el Congreso anual de ESPEN se celebr\u00f3 en Lisboa, y en este se realiz\u00f3 una serie de entrevistas con reconocidos expertos de Am\u00e9rica Latina. M\u00e1s abajo podr\u00e1 ver algunos videos y m\u00e1s reflexiones sobre las opiniones de estos expertos.<\/p>\n<p>\u00bfCu\u00e1les son los recursos fundamentales para disminuir la frecuencia de la desnutrici\u00f3n relacionada con enfermedades?<\/p>\n<p>Carolina M\u00e9ndez Mart\u00ednez:<br \/>\nLa funci\u00f3n del equipo debe estar dirigida a responder a las necesidades del paciente. En la unidad de cuidados intensivos, el objetivo deber\u00eda ser trabajar como un equipo para que cada uno de nosotros, con lo que cada uno tiene para aportar, pueda generar y poner en marcha el apoyo adecuado. La situaci\u00f3n ideal, desde el punto de vista de un nutricionista, ser\u00eda contar con m\u00e1s personal. La cantidad de nutricionistas cl\u00ednicos en las instituciones es muy limitada. Sobre la base de encuestas recientes, vemos que hay un nutricionista cada 50 a 100 pacientes. De forma que detectar la desnutrici\u00f3n con nuestras competencias no es tarea f\u00e1cil. Ser\u00eda ideal que pudi\u00e9ramos contar con m\u00e1s profesionales capacitados y que poseyeran las herramientas adecuadas para tratar a los pacientes.<\/p>\n<p>Dr. Mario Ignacio Perman:<br \/>\nEn las facultades de medicina, la nutrici\u00f3n no es una de las disciplinas que se estudian en profundidad. Es m\u00e1s bien superficial. No se le dedica el tiempo necesario o no se proporciona la informaci\u00f3n suficiente, lo que conduce a la falta de conocimiento y a complicaciones en el tratamiento de los pacientes. Los expertos en nutrici\u00f3n son como los chefs, pero para poder cocinar en un restaurante debe existir un equipo, un grupo, que conozca las necesidades del consumidor. La educaci\u00f3n implica ense\u00f1ar los diferentes aspectos de la nutrici\u00f3n cl\u00ednica y proporcionar los recursos para implementarla.<\/p>\n<p>Dr. Roger Enrique Riofr\u00edo:<br \/>\nLa educaci\u00f3n es uno de los mayores problemas. Al menos, en Ecuador, la educaci\u00f3n es muy deficiente. No existe la formaci\u00f3n en nutrici\u00f3n. Las universidades no ofrecen cursos de formaci\u00f3n en nutrici\u00f3n, como tampoco lo hacen otros sistemas educativos de posgrado. Esta es una de las piezas claves que falta para generar consciencia sobre la importancia de la nutrici\u00f3n.<\/p>\n<p>Dr. Alfredo Matos Adames:<br \/>\nEn mi opini\u00f3n, la ra\u00edz del problema est\u00e1 en la educaci\u00f3n, en la formaci\u00f3n deficiente sobre nutrici\u00f3n cl\u00ednica que se ofrece a los estudiantes de medicina. Cuando estos estudiantes se convierten en m\u00e9dicos y comienzan a trabajar en hospitales, tienen muy poco o ning\u00fan conocimiento acerca de qu\u00e9 significa la nutrici\u00f3n cl\u00ednica. Y esto no es exclusivo de las facultades de medicina. Tambi\u00e9n se aplica a las facultades de nutrici\u00f3n, enfermer\u00eda y farmacia que forman profesionales, pero que tienen muy poco conocimiento sobre nutrici\u00f3n cl\u00ednica.<\/p>\n<p><a href=\"https:\/\/lam.unitedforclinicalnutrition.com\/es-mx\/video\/carolina-mendez-martinez\/\">Carolina M\u00e9ndez Mart\u00ednez, entrevista en la que aporta reflexiones sobre el manejo y la administraci\u00f3n de terapia nutricional<\/a><\/p>\n<p><a href=\"https:\/\/lam.unitedforclinicalnutrition.com\/es-mx\/video\/dr-mario-ignacio-perman\/\">Dr. Mario Ignacio Perman, entrevista en la que aporta reflexiones sobre el manejo y la administraci\u00f3n de terapia nutricional<\/a><\/p>\n<p><a href=\"https:\/\/lam.unitedforclinicalnutrition.com\/es-mx\/video\/dr-roger-riofrio\/\">Dr. Roger Enrique Riofrio, entrevista en la que aporta reflexiones sobre el manejo y la administraci\u00f3n de terapia nutricional<\/a><\/p>\n<p><a href=\"https:\/\/lam.unitedforclinicalnutrition.com\/es-mx\/video\/dr-guillermo-carlos-contreras-and-dr-alfredo-matos-adames\/\">Dr. Alfredo Matos Adames, entrevista en la que aporta reflexiones sobre el manejo y la administraci\u00f3n de terapia nutricional<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durante el congreso anual de la Sociedad Europea de Nutrici\u00f3n Cl\u00ednica y Metabolismo (ESPEN, seg\u00fan sus siglas en ingl\u00e9s), varios expertos aportaron su opini\u00f3n sobre los cambios fundamentales que se necesitan en los sistemas hospitalarios actuales para implementar la terapia nutricional. Estuvieron de acuerdo en que, para combatir la desnutrici\u00f3n relacionada con enfermedades, tanto la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":512,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[45,7],"tags":[],"class_list":["post-449","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-articulo-3","category-nutricion-clinica"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Conozca m\u00e1s sobre las \u00e1reas de mejora en un entorno hospitalario - Unidos por la Nutrici\u00f3n Cl\u00ednica | M\u00e9xico<\/title>\n<meta name=\"description\" content=\"Durante el congreso anual de la Sociedad Europea de Nutrici\u00f3n Cl\u00ednica y Metabolismo (ESPEN, seg\u00fan sus siglas en ingl\u00e9s), varios expertos aportaron su\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lam.unitedforclinicalnutrition.com\/es-mx\/conozca-mas-sobre-las-areas-de-mejora-en-un-entorno-hospitalario\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Conozca m\u00e1s sobre las \u00e1reas de mejora en un entorno hospitalario - Unidos por la Nutrici\u00f3n Cl\u00ednica | M\u00e9xico\" \/>\n<meta property=\"og:description\" content=\"Durante el congreso anual de la Sociedad Europea de Nutrici\u00f3n Cl\u00ednica y Metabolismo (ESPEN, seg\u00fan sus siglas en ingl\u00e9s), varios expertos aportaron su\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lam.unitedforclinicalnutrition.com\/es-mx\/conozca-mas-sobre-las-areas-de-mejora-en-un-entorno-hospitalario\/\" \/>\n<meta property=\"og:site_name\" content=\"Unidos por la Nutrici\u00f3n Cl\u00ednica | M\u00e9xico\" \/>\n<meta property=\"article:published_time\" content=\"2017-05-08T00:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-03-10T23:03:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lam.unitedforclinicalnutrition.com\/es-mx\/wp-content\/uploads\/sites\/5\/2018\/05\/170410_articleeducation_image_carolina.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"856\" \/>\n\t<meta property=\"og:image:height\" content=\"386\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"actycrea\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"actycrea\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/es-mx\\\/conozca-mas-sobre-las-areas-de-mejora-en-un-entorno-hospitalario\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/es-mx\\\/conozca-mas-sobre-las-areas-de-mejora-en-un-entorno-hospitalario\\\/\"},\"author\":{\"name\":\"actycrea\",\"@id\":\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/es-mx\\\/#\\\/schema\\\/person\\\/047903fcf38a9d211770ad89bfd1360b\"},\"headline\":\"Conozca m\u00e1s sobre las \u00e1reas de mejora en un entorno hospitalario\",\"datePublished\":\"2017-05-08T00:00:00+00:00\",\"dateModified\":\"2020-03-10T23:03:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/es-mx\\\/conozca-mas-sobre-las-areas-de-mejora-en-un-entorno-hospitalario\\\/\"},\"wordCount\":785,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/es-mx\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/es-mx\\\/conozca-mas-sobre-las-areas-de-mejora-en-un-entorno-hospitalario\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/es-mx\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2018\\\/05\\\/170410_articleeducation_image_carolina.jpg\",\"articleSection\":[\"Art\u00edculos\",\"Nutrici\u00f3n Cl\u00ednica\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/es-mx\\\/conozca-mas-sobre-las-areas-de-mejora-en-un-entorno-hospitalario\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/es-mx\\\/conozca-mas-sobre-las-areas-de-mejora-en-un-entorno-hospitalario\\\/\",\"url\":\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/es-mx\\\/conozca-mas-sobre-las-areas-de-mejora-en-un-entorno-hospitalario\\\/\",\"name\":\"Conozca m\u00e1s sobre las \u00e1reas de mejora en un entorno hospitalario - Unidos por la Nutrici\u00f3n Cl\u00ednica | M\u00e9xico\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/es-mx\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/es-mx\\\/conozca-mas-sobre-las-areas-de-mejora-en-un-entorno-hospitalario\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/es-mx\\\/conozca-mas-sobre-las-areas-de-mejora-en-un-entorno-hospitalario\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/es-mx\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2018\\\/05\\\/170410_articleeducation_image_carolina.jpg\",\"datePublished\":\"2017-05-08T00:00:00+00:00\",\"dateModified\":\"2020-03-10T23:03:56+00:00\",\"description\":\"Durante el congreso anual de la Sociedad Europea de Nutrici\u00f3n Cl\u00ednica y Metabolismo (ESPEN, seg\u00fan sus siglas en ingl\u00e9s), varios expertos aportaron su\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/es-mx\\\/conozca-mas-sobre-las-areas-de-mejora-en-un-entorno-hospitalario\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/es-mx\\\/conozca-mas-sobre-las-areas-de-mejora-en-un-entorno-hospitalario\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/es-mx\\\/conozca-mas-sobre-las-areas-de-mejora-en-un-entorno-hospitalario\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/es-mx\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2018\\\/05\\\/170410_articleeducation_image_carolina.jpg\",\"contentUrl\":\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/es-mx\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2018\\\/05\\\/170410_articleeducation_image_carolina.jpg\",\"width\":856,\"height\":386},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/es-mx\\\/conozca-mas-sobre-las-areas-de-mejora-en-un-entorno-hospitalario\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/es-mx\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Conozca m\u00e1s sobre las \u00e1reas de mejora en un entorno hospitalario\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/es-mx\\\/#website\",\"url\":\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/es-mx\\\/\",\"name\":\"Unidos por la Nutrici\u00f3n Cl\u00ednica | M\u00e9xico\",\"description\":\"Es una iniciativa creada por Fresenius Kabi para trabajar en conjunto con los profesionales de la salud.\",\"publisher\":{\"@id\":\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/es-mx\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/es-mx\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/es-mx\\\/#organization\",\"name\":\"Fresenius Kabi AG\",\"url\":\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/es-mx\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/es-mx\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/es-mx\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2018\\\/05\\\/Downloads_en_0000_Logo_edit_spanish.jpg\",\"contentUrl\":\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/es-mx\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2018\\\/05\\\/Downloads_en_0000_Logo_edit_spanish.jpg\",\"width\":600,\"height\":400,\"caption\":\"Fresenius Kabi AG\"},\"image\":{\"@id\":\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/es-mx\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/es-mx\\\/#\\\/schema\\\/person\\\/047903fcf38a9d211770ad89bfd1360b\",\"name\":\"actycrea\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/525bdeedb358bff65b8fc0b894d469f1ddd5b5113ca5c201756ec4f13ca61bdc?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/525bdeedb358bff65b8fc0b894d469f1ddd5b5113ca5c201756ec4f13ca61bdc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/525bdeedb358bff65b8fc0b894d469f1ddd5b5113ca5c201756ec4f13ca61bdc?s=96&d=mm&r=g\",\"caption\":\"actycrea\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Conozca m\u00e1s sobre las \u00e1reas de mejora en un entorno hospitalario - Unidos por la Nutrici\u00f3n Cl\u00ednica | M\u00e9xico","description":"Durante el congreso anual de la Sociedad Europea de Nutrici\u00f3n Cl\u00ednica y Metabolismo (ESPEN, seg\u00fan sus siglas en ingl\u00e9s), varios expertos aportaron su","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lam.unitedforclinicalnutrition.com\/es-mx\/conozca-mas-sobre-las-areas-de-mejora-en-un-entorno-hospitalario\/","og_locale":"es_MX","og_type":"article","og_title":"Conozca m\u00e1s sobre las \u00e1reas de mejora en un entorno hospitalario - Unidos por la Nutrici\u00f3n Cl\u00ednica | M\u00e9xico","og_description":"Durante el congreso anual de la Sociedad Europea de Nutrici\u00f3n Cl\u00ednica y Metabolismo (ESPEN, seg\u00fan sus siglas en ingl\u00e9s), varios expertos aportaron su","og_url":"https:\/\/lam.unitedforclinicalnutrition.com\/es-mx\/conozca-mas-sobre-las-areas-de-mejora-en-un-entorno-hospitalario\/","og_site_name":"Unidos por la Nutrici\u00f3n Cl\u00ednica | M\u00e9xico","article_published_time":"2017-05-08T00:00:00+00:00","article_modified_time":"2020-03-10T23:03:56+00:00","og_image":[{"width":856,"height":386,"url":"https:\/\/lam.unitedforclinicalnutrition.com\/es-mx\/wp-content\/uploads\/sites\/5\/2018\/05\/170410_articleeducation_image_carolina.jpg","type":"image\/jpeg"}],"author":"actycrea","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"actycrea","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lam.unitedforclinicalnutrition.com\/es-mx\/conozca-mas-sobre-las-areas-de-mejora-en-un-entorno-hospitalario\/#article","isPartOf":{"@id":"https:\/\/lam.unitedforclinicalnutrition.com\/es-mx\/conozca-mas-sobre-las-areas-de-mejora-en-un-entorno-hospitalario\/"},"author":{"name":"actycrea","@id":"https:\/\/lam.unitedforclinicalnutrition.com\/es-mx\/#\/schema\/person\/047903fcf38a9d211770ad89bfd1360b"},"headline":"Conozca m\u00e1s sobre las \u00e1reas de mejora en un entorno hospitalario","datePublished":"2017-05-08T00:00:00+00:00","dateModified":"2020-03-10T23:03:56+00:00","mainEntityOfPage":{"@id":"https:\/\/lam.unitedforclinicalnutrition.com\/es-mx\/conozca-mas-sobre-las-areas-de-mejora-en-un-entorno-hospitalario\/"},"wordCount":785,"commentCount":0,"publisher":{"@id":"https:\/\/lam.unitedforclinicalnutrition.com\/es-mx\/#organization"},"image":{"@id":"https:\/\/lam.unitedforclinicalnutrition.com\/es-mx\/conozca-mas-sobre-las-areas-de-mejora-en-un-entorno-hospitalario\/#primaryimage"},"thumbnailUrl":"https:\/\/lam.unitedforclinicalnutrition.com\/es-mx\/wp-content\/uploads\/sites\/5\/2018\/05\/170410_articleeducation_image_carolina.jpg","articleSection":["Art\u00edculos","Nutrici\u00f3n Cl\u00ednica"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/lam.unitedforclinicalnutrition.com\/es-mx\/conozca-mas-sobre-las-areas-de-mejora-en-un-entorno-hospitalario\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/lam.unitedforclinicalnutrition.com\/es-mx\/conozca-mas-sobre-las-areas-de-mejora-en-un-entorno-hospitalario\/","url":"https:\/\/lam.unitedforclinicalnutrition.com\/es-mx\/conozca-mas-sobre-las-areas-de-mejora-en-un-entorno-hospitalario\/","name":"Conozca m\u00e1s sobre las \u00e1reas de mejora en un entorno hospitalario - Unidos por la Nutrici\u00f3n Cl\u00ednica | M\u00e9xico","isPartOf":{"@id":"https:\/\/lam.unitedforclinicalnutrition.com\/es-mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lam.unitedforclinicalnutrition.com\/es-mx\/conozca-mas-sobre-las-areas-de-mejora-en-un-entorno-hospitalario\/#primaryimage"},"image":{"@id":"https:\/\/lam.unitedforclinicalnutrition.com\/es-mx\/conozca-mas-sobre-las-areas-de-mejora-en-un-entorno-hospitalario\/#primaryimage"},"thumbnailUrl":"https:\/\/lam.unitedforclinicalnutrition.com\/es-mx\/wp-content\/uploads\/sites\/5\/2018\/05\/170410_articleeducation_image_carolina.jpg","datePublished":"2017-05-08T00:00:00+00:00","dateModified":"2020-03-10T23:03:56+00:00","description":"Durante el congreso anual de la Sociedad Europea de Nutrici\u00f3n Cl\u00ednica y Metabolismo (ESPEN, seg\u00fan sus siglas en ingl\u00e9s), varios expertos aportaron su","breadcrumb":{"@id":"https:\/\/lam.unitedforclinicalnutrition.com\/es-mx\/conozca-mas-sobre-las-areas-de-mejora-en-un-entorno-hospitalario\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lam.unitedforclinicalnutrition.com\/es-mx\/conozca-mas-sobre-las-areas-de-mejora-en-un-entorno-hospitalario\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/lam.unitedforclinicalnutrition.com\/es-mx\/conozca-mas-sobre-las-areas-de-mejora-en-un-entorno-hospitalario\/#primaryimage","url":"https:\/\/lam.unitedforclinicalnutrition.com\/es-mx\/wp-content\/uploads\/sites\/5\/2018\/05\/170410_articleeducation_image_carolina.jpg","contentUrl":"https:\/\/lam.unitedforclinicalnutrition.com\/es-mx\/wp-content\/uploads\/sites\/5\/2018\/05\/170410_articleeducation_image_carolina.jpg","width":856,"height":386},{"@type":"BreadcrumbList","@id":"https:\/\/lam.unitedforclinicalnutrition.com\/es-mx\/conozca-mas-sobre-las-areas-de-mejora-en-un-entorno-hospitalario\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/lam.unitedforclinicalnutrition.com\/es-mx\/"},{"@type":"ListItem","position":2,"name":"Conozca m\u00e1s sobre las \u00e1reas de mejora en un entorno hospitalario"}]},{"@type":"WebSite","@id":"https:\/\/lam.unitedforclinicalnutrition.com\/es-mx\/#website","url":"https:\/\/lam.unitedforclinicalnutrition.com\/es-mx\/","name":"Unidos por la Nutrici\u00f3n Cl\u00ednica | M\u00e9xico","description":"Es una iniciativa creada por Fresenius Kabi para trabajar en conjunto con los profesionales de la salud.","publisher":{"@id":"https:\/\/lam.unitedforclinicalnutrition.com\/es-mx\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lam.unitedforclinicalnutrition.com\/es-mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/lam.unitedforclinicalnutrition.com\/es-mx\/#organization","name":"Fresenius Kabi AG","url":"https:\/\/lam.unitedforclinicalnutrition.com\/es-mx\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/lam.unitedforclinicalnutrition.com\/es-mx\/#\/schema\/logo\/image\/","url":"https:\/\/lam.unitedforclinicalnutrition.com\/es-mx\/wp-content\/uploads\/sites\/5\/2018\/05\/Downloads_en_0000_Logo_edit_spanish.jpg","contentUrl":"https:\/\/lam.unitedforclinicalnutrition.com\/es-mx\/wp-content\/uploads\/sites\/5\/2018\/05\/Downloads_en_0000_Logo_edit_spanish.jpg","width":600,"height":400,"caption":"Fresenius Kabi AG"},"image":{"@id":"https:\/\/lam.unitedforclinicalnutrition.com\/es-mx\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/lam.unitedforclinicalnutrition.com\/es-mx\/#\/schema\/person\/047903fcf38a9d211770ad89bfd1360b","name":"actycrea","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/525bdeedb358bff65b8fc0b894d469f1ddd5b5113ca5c201756ec4f13ca61bdc?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/525bdeedb358bff65b8fc0b894d469f1ddd5b5113ca5c201756ec4f13ca61bdc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/525bdeedb358bff65b8fc0b894d469f1ddd5b5113ca5c201756ec4f13ca61bdc?s=96&d=mm&r=g","caption":"actycrea"}}]}},"_links":{"self":[{"href":"https:\/\/lam.unitedforclinicalnutrition.com\/es-mx\/wp-json\/wp\/v2\/posts\/449","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lam.unitedforclinicalnutrition.com\/es-mx\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lam.unitedforclinicalnutrition.com\/es-mx\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lam.unitedforclinicalnutrition.com\/es-mx\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lam.unitedforclinicalnutrition.com\/es-mx\/wp-json\/wp\/v2\/comments?post=449"}],"version-history":[{"count":0,"href":"https:\/\/lam.unitedforclinicalnutrition.com\/es-mx\/wp-json\/wp\/v2\/posts\/449\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lam.unitedforclinicalnutrition.com\/es-mx\/wp-json\/wp\/v2\/media\/512"}],"wp:attachment":[{"href":"https:\/\/lam.unitedforclinicalnutrition.com\/es-mx\/wp-json\/wp\/v2\/media?parent=449"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lam.unitedforclinicalnutrition.com\/es-mx\/wp-json\/wp\/v2\/categories?post=449"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lam.unitedforclinicalnutrition.com\/es-mx\/wp-json\/wp\/v2\/tags?post=449"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}