{"id":375,"date":"2015-03-31T00:00:00","date_gmt":"2015-03-31T00:00:00","guid":{"rendered":"https:\/\/lam.unitedforclinicalnutrition.com\/co\/bases-de-la-nutricion\/"},"modified":"2021-11-10T12:40:06","modified_gmt":"2021-11-10T12:40:06","slug":"bases-de-la-nutricion","status":"publish","type":"post","link":"https:\/\/lam.unitedforclinicalnutrition.com\/es-co\/bases-de-la-nutricion\/","title":{"rendered":"Bases de la Nutrici\u00f3n"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-376\" src=\"https:\/\/lam.unitedforclinicalnutrition.com\/es-co\/wp-content\/uploads\/sites\/7\/2018\/06\/mood_nutrition_basics.jpg\" alt=\"\" width=\"856\" height=\"571\" srcset=\"https:\/\/lam.unitedforclinicalnutrition.com\/es-co\/wp-content\/uploads\/sites\/7\/2018\/06\/mood_nutrition_basics.jpg 856w, https:\/\/lam.unitedforclinicalnutrition.com\/es-co\/wp-content\/uploads\/sites\/7\/2018\/06\/mood_nutrition_basics-300x200.jpg 300w, https:\/\/lam.unitedforclinicalnutrition.com\/es-co\/wp-content\/uploads\/sites\/7\/2018\/06\/mood_nutrition_basics-768x512.jpg 768w, https:\/\/lam.unitedforclinicalnutrition.com\/es-co\/wp-content\/uploads\/sites\/7\/2018\/06\/mood_nutrition_basics-562x375.jpg 562w\" sizes=\"auto, (max-width: 856px) 100vw, 856px\" \/><\/p>\n<p>Una dieta saludable est\u00e1 normalmente compuesta de macronutrientes, micronutrientes y l\u00edquidos. Cuando son consumidos de forma balanceada, normalmente cumple con los requerimientos metab\u00f3licos diarios del cuerpo.<\/p>\n<h3>Macronutrientes<\/h3>\n<p>Los macronutrientes son sustancias necesarias para el crecimiento, metabolismo y otras funciones normales del organismo. Estos nutrientes son normalmente consumidos en grandes cantidades para proporcionar gran cantidad de energ\u00eda y reparaci\u00f3n celular.<\/p>\n<p>Los macronutrientes est\u00e1n compuestos de:<\/p>\n<ul>\n<li><strong>Carbohidratos<\/strong>, compuestos org\u00e1nicos clasificados seg\u00fan el n\u00famero de sac\u00e1ridos, como monosac\u00e1ridos, disac\u00e1ridos y polisac\u00e1ridos los cuales est\u00e1n compuestos de carbono, hidr\u00f3geno, ox\u00edgeno y tienen varias funciones en los organismos vivos, como producci\u00f3n de energ\u00eda,componentes estructurales y la columna vertebral del ARN. Los carbohidratos son necesarios para el funcionamiento normal del sistema nervioso central, coraz\u00f3n, ri\u00f1ones y \u00a0m\u00fasculos. Aproximadamente el 45 % a 65 % del consumo diario de calor\u00edas deber\u00eda ser en la forma de carbohidratos.<\/li>\n<\/ul>\n<ul>\n<li><strong>Los l\u00edpidos<\/strong>\u00a0tienen una serie de funciones en el cuerpo, como fuente de almacenamiento de energ\u00eda, actuando como componentes estructurales de las membranas celulares, aportando al desarrollo celular, ayudando con la trasmisi\u00f3n c\u00e9lulas nerviosas protegiendo los \u00f3rganos internos, brindando aislamiento para mantener el calor del cuerpo, y ayudando en la absorci\u00f3n de las vitaminas liposolubles: A, D, K, E. Adem\u00e1s, los l\u00edpidos sirven como un medio para el almacenamiento de energ\u00eda. Otros l\u00edpidos influyen en las alarmas celulares, pueden regular la expresi\u00f3n de los genes, sirve como un marcador para el reconocimiento celular o modular\u00a0 mediadores l\u00edpidicos. Los \u00e1cidos grasos son los elementos claves de los l\u00edpidos y se clasifican de acuerdo a la caracter\u00edsticas estructurales, de acuerdo a \u00a0la extensi\u00f3n de la cadena de carbono, la presencia y ubicaci\u00f3n de los dobles enlaces en la cadena, y su configuraci\u00f3n (por ejemplo, Cis o trans). Pueden ser clasificados como saturados (sin dobles enlaces), no saturados (un doble enlace), o poli-insaturados (m\u00e1s de un doble enlace).<\/li>\n<\/ul>\n<ul>\n<li><strong>Prote\u00ednas<\/strong>, compuestas de uno o m\u00e1s cadenas de amino\u00e1cidos, son la fuente primaria del nitr\u00f3geno, brindan nutrientes esenciales para el cuerpo, y ofrecen soporte estructural que incluye la queratina para la piel y el cabello, col\u00e1geno para los tejidos conectivos, elastina, actina y miosina para los m\u00fasculos, y glicoprote\u00ednas para las membranas de las c\u00e9lulas. Las prote\u00ednas tambi\u00e9n tienen un rol funcional como enzimas; las hormonas para la regulaci\u00f3n metab\u00f3lica; la hemoglobina y transferrina para el transporte del ox\u00edgeno y hierro; albumina para regular el volumen de la sangre; y anticuerpos para el sistema inmune. Por ejemplo, la Glutamina est\u00e1 involucrada en varios procesos metab\u00f3licos. Como en el metabolismo de prote\u00ednas y glucosa, Glutamina sirve como un transportador para el nitr\u00f3geno y el carbono entre los \u00f3rganos, actuando como un precursor para los nucle\u00f3tidos, ayudando a la protecci\u00f3n celular, y regulando el equilibrio \u00e1cido.Los amino\u00e1cidos se dividen en 3 tipos, que incluyen:<\/li>\n<li><strong>Amino\u00e1cidos esenciales<\/strong>\u00a0que no pueden ser producidos por el cuerpo y deben ser obtenidos a trav\u00e9s de los alimentos.<\/li>\n<li><strong>Amino\u00e1cidos condicionales\u00a0<\/strong>que no pueden ser producidos por el cuerpo durante las condiciones especiales, tales como la enfermedad.<\/li>\n<li><strong>Amino\u00e1cidos no esenciales<\/strong>\u00a0que pueden ser sintetizados por el cuerpo.<\/li>\n<\/ul>\n<h3>Micronutrientes<\/h3>\n<p>Los micronutrientes son necesarios para el mantenimiento del metabolismo normal y el estado antioxidante. Estos nutrientes son necesarios para la utilizaci\u00f3n eficiente de los macronutrientes.<\/p>\n<p>Los micronutrientes son vitaminas, oligoelementos y minerales:<\/p>\n<ul>\n<li>Las\u00a0<strong>vitaminas<\/strong>\u00a0se categorizan en soluble en agua y liposoluble. Las vitaminas solubles en agua requieren remplazo regular en el cuerpo, mientras que las vitaminas liposolubles se almacenan en el h\u00edgado y los tejidos grasos, y son eliminados de manera m\u00e1s lenta:\n<ul>\n<li>\u200b<strong>Las vitaminas solubles en agua\u00a0<\/strong>son itaminas B y C. Las vitaminas B act\u00faan en el metabolismo de los carbohidratos, prote\u00ednas, l\u00edpidos y \u00e1cidos nucleicos, de este modo contribuir con la producci\u00f3n de energ\u00eda, neurotransmisi\u00f3n y la formaci\u00f3n de los gl\u00f3bulos rojos. La vitamina C act\u00faa como un antioxidante que ayuda a proteger las c\u00e9lulas del da\u00f1o causado por radicales libres.<\/li>\n<li><strong>Las Vitaminas liposolubles\u00a0<\/strong>vitamina A, D, E y K. La vitamina A es un componente integral de las c\u00e9lulas conos y bastones en el ojo, y es esencial para la diferenciaci\u00f3n y reproducci\u00f3n de la c\u00e9lula, particularmente durante la embriog\u00e9nesis. Las vitaminas D presenta varias funciones, especialmente en el mantenimiento del equilibrio del calcio y la salud de los huesos. La vitamina E es un antioxidante potente y eliminador del radical libre. La vitamina K es necesario para el funcionamiento apropiado de la cascada de la coagulaci\u00f3n.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p>Existen sustancias inorg\u00e1nicas requeridas para los procesos funcionales y estructurales del organismo \u00a0procesos del cuerpo. Estos minerales son sodio, f\u00f3sforo, calcio, hierro, potasio y magnesio.<\/p>\n<ul>\n<li>Los minerales tienen varias funciones diferentes, tales como regulaci\u00f3n de l\u00edquidos, estructura \u00f3sea, movimiento de los m\u00fasculos y funcionamiento del sistema nervioso<\/li>\n<li>Los oligoelementos importantes requeridos por el organismo:\n<ul>\n<li>\u200bEl\u00a0<strong>Hierro<\/strong>\u00a0asegura que la hemoglobina y mioglobina trabajen adecuadamente para combinar el ox\u00edgeno.<\/li>\n<li>El\u00a0<strong>Zinc<\/strong>\u00a0es un micronutriente para la v\u00eda metab\u00f3lica, la estabilizaci\u00f3n de las membranas de las c\u00e9lulas y la funci\u00f3n inmune.<\/li>\n<li>El\u00a0<strong>Selenio<\/strong>\u00a0esta involucrado \u00a0en la protecci\u00f3n del antioxidante y es importante en la conversi\u00f3n de la hormona tiroidea.<\/li>\n<li>El\u00a0<strong>Iodo\u00a0<\/strong>es un elemento de las hormonas tiroideas, de este modo influencia en el metabolismo de la energ\u00eda, los procesos de crecimiento celular y el desarrollo fetal.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<h3>Agua<\/h3>\n<p>El agua es cuantitativamente el componente m\u00e1s importante del cuerpo humano, teniendo en cuenta que corresponde al \u00a050 % &#8211; 60 % del peso corporal, distribuido en los compartimientos de fluido intra y extracelular. La cantidad adecuada de agua para un cuerpo permite los procesos del cuerpo, tales como el flujo sangu\u00edneo y el sistema linf\u00e1tico para que funcione con fluidez, haciendo del agua un nutriente crucial para la salud y la supervivencia.<\/p>\n<p>Procesos fidiol\u00f3gicos donde el agua est\u00e1 involucrada:<\/p>\n<ul>\n<li>Balance de l\u00edquidos<\/li>\n<li>Impulsos del sistema nervioso nervio<\/li>\n<li>Contracciones del m\u00fasculo<\/li>\n<li>Transporte de nutrientes<\/li>\n<li>Eliminaci\u00f3n de residuos<\/li>\n<li>Reacci\u00f3n qu\u00edmica<\/li>\n<\/ul>\n<p>Estos son solo unos cuantos de las funciones que juega el agua en el cuerpo. El agua es un nutriente cr\u00edtico para la salud y la supervivencia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una dieta saludable est\u00e1 normalmente compuesta de macronutrientes, micronutrientes y l\u00edquidos. Cuando son consumidos de forma balanceada, normalmente cumple con los requerimientos metab\u00f3licos diarios del cuerpo. Macronutrientes Los macronutrientes son sustancias necesarias para el crecimiento, metabolismo y otras funciones normales del organismo. Estos nutrientes son normalmente consumidos en grandes cantidades para proporcionar gran cantidad de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":516,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[49,7],"tags":[],"class_list":["post-375","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-articulo-3","category-nutricion-clinica"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bases de la Nutrici\u00f3n - Unidos por la Nutrici\u00f3n Cl\u00ednica | Colombia<\/title>\n<meta name=\"description\" content=\"Una dieta saludable est\u00e1 normalmente compuesta de macronutrientes, micronutrientes y l\u00edquidos. Cuando son consumidos de forma balanceada, normalmente\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lam.unitedforclinicalnutrition.com\/es-co\/bases-de-la-nutricion\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bases de la Nutrici\u00f3n - Unidos por la Nutrici\u00f3n Cl\u00ednica | Colombia\" \/>\n<meta property=\"og:description\" content=\"Una dieta saludable est\u00e1 normalmente compuesta de macronutrientes, micronutrientes y l\u00edquidos. Cuando son consumidos de forma balanceada, normalmente\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lam.unitedforclinicalnutrition.com\/es-co\/bases-de-la-nutricion\/\" \/>\n<meta property=\"og:site_name\" content=\"Unidos por la Nutrici\u00f3n Cl\u00ednica | Colombia\" \/>\n<meta property=\"article:published_time\" content=\"2015-03-31T00:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-11-10T12:40:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lam.unitedforclinicalnutrition.com\/es-co\/wp-content\/uploads\/sites\/7\/2018\/06\/mood_nutrition_basics-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"856\" \/>\n\t<meta property=\"og:image:height\" content=\"571\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"actycrea\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"actycrea\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/es-co\\\/bases-de-la-nutricion\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/es-co\\\/bases-de-la-nutricion\\\/\"},\"author\":{\"name\":\"actycrea\",\"@id\":\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/es-co\\\/#\\\/schema\\\/person\\\/047903fcf38a9d211770ad89bfd1360b\"},\"headline\":\"Bases de la Nutrici\u00f3n\",\"datePublished\":\"2015-03-31T00:00:00+00:00\",\"dateModified\":\"2021-11-10T12:40:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/es-co\\\/bases-de-la-nutricion\\\/\"},\"wordCount\":1094,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/es-co\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/es-co\\\/bases-de-la-nutricion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/es-co\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2018\\\/06\\\/mood_nutrition_basics-2.jpg\",\"articleSection\":[\"Art\u00edculos\",\"Nutrici\u00f3n Cl\u00ednica\"],\"inLanguage\":\"es-CO\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/es-co\\\/bases-de-la-nutricion\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/es-co\\\/bases-de-la-nutricion\\\/\",\"url\":\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/es-co\\\/bases-de-la-nutricion\\\/\",\"name\":\"Bases de la Nutrici\u00f3n - Unidos por la Nutrici\u00f3n Cl\u00ednica | Colombia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/es-co\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/es-co\\\/bases-de-la-nutricion\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/es-co\\\/bases-de-la-nutricion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/es-co\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2018\\\/06\\\/mood_nutrition_basics-2.jpg\",\"datePublished\":\"2015-03-31T00:00:00+00:00\",\"dateModified\":\"2021-11-10T12:40:06+00:00\",\"description\":\"Una dieta saludable est\u00e1 normalmente compuesta de macronutrientes, micronutrientes y l\u00edquidos. Cuando son consumidos de forma balanceada, normalmente\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/es-co\\\/bases-de-la-nutricion\\\/#breadcrumb\"},\"inLanguage\":\"es-CO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/es-co\\\/bases-de-la-nutricion\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/es-co\\\/bases-de-la-nutricion\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/es-co\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2018\\\/06\\\/mood_nutrition_basics-2.jpg\",\"contentUrl\":\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/es-co\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2018\\\/06\\\/mood_nutrition_basics-2.jpg\",\"width\":856,\"height\":571},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/es-co\\\/bases-de-la-nutricion\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/es-co\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bases de la Nutrici\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/es-co\\\/#website\",\"url\":\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/es-co\\\/\",\"name\":\"Unidos por la Nutrici\u00f3n Cl\u00ednica | Colombia\",\"description\":\"Es una iniciativa creada por Fresenius Kabi para trabajar en conjunto con los profesionales de la salud.\",\"publisher\":{\"@id\":\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/es-co\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/es-co\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CO\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/es-co\\\/#organization\",\"name\":\"Fresenius Kabi AG\",\"url\":\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/es-co\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/es-co\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/es-co\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2018\\\/06\\\/Downloads_en_0000_Logo_edit_spanish.jpg\",\"contentUrl\":\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/es-co\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2018\\\/06\\\/Downloads_en_0000_Logo_edit_spanish.jpg\",\"width\":600,\"height\":400,\"caption\":\"Fresenius Kabi AG\"},\"image\":{\"@id\":\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/es-co\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lam.unitedforclinicalnutrition.com\\\/es-co\\\/#\\\/schema\\\/person\\\/047903fcf38a9d211770ad89bfd1360b\",\"name\":\"actycrea\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/525bdeedb358bff65b8fc0b894d469f1ddd5b5113ca5c201756ec4f13ca61bdc?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/525bdeedb358bff65b8fc0b894d469f1ddd5b5113ca5c201756ec4f13ca61bdc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/525bdeedb358bff65b8fc0b894d469f1ddd5b5113ca5c201756ec4f13ca61bdc?s=96&d=mm&r=g\",\"caption\":\"actycrea\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bases de la Nutrici\u00f3n - Unidos por la Nutrici\u00f3n Cl\u00ednica | Colombia","description":"Una dieta saludable est\u00e1 normalmente compuesta de macronutrientes, micronutrientes y l\u00edquidos. Cuando son consumidos de forma balanceada, normalmente","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lam.unitedforclinicalnutrition.com\/es-co\/bases-de-la-nutricion\/","og_locale":"es_ES","og_type":"article","og_title":"Bases de la Nutrici\u00f3n - Unidos por la Nutrici\u00f3n Cl\u00ednica | Colombia","og_description":"Una dieta saludable est\u00e1 normalmente compuesta de macronutrientes, micronutrientes y l\u00edquidos. Cuando son consumidos de forma balanceada, normalmente","og_url":"https:\/\/lam.unitedforclinicalnutrition.com\/es-co\/bases-de-la-nutricion\/","og_site_name":"Unidos por la Nutrici\u00f3n Cl\u00ednica | Colombia","article_published_time":"2015-03-31T00:00:00+00:00","article_modified_time":"2021-11-10T12:40:06+00:00","og_image":[{"width":856,"height":571,"url":"https:\/\/lam.unitedforclinicalnutrition.com\/es-co\/wp-content\/uploads\/sites\/7\/2018\/06\/mood_nutrition_basics-2.jpg","type":"image\/jpeg"}],"author":"actycrea","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"actycrea","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lam.unitedforclinicalnutrition.com\/es-co\/bases-de-la-nutricion\/#article","isPartOf":{"@id":"https:\/\/lam.unitedforclinicalnutrition.com\/es-co\/bases-de-la-nutricion\/"},"author":{"name":"actycrea","@id":"https:\/\/lam.unitedforclinicalnutrition.com\/es-co\/#\/schema\/person\/047903fcf38a9d211770ad89bfd1360b"},"headline":"Bases de la Nutrici\u00f3n","datePublished":"2015-03-31T00:00:00+00:00","dateModified":"2021-11-10T12:40:06+00:00","mainEntityOfPage":{"@id":"https:\/\/lam.unitedforclinicalnutrition.com\/es-co\/bases-de-la-nutricion\/"},"wordCount":1094,"commentCount":0,"publisher":{"@id":"https:\/\/lam.unitedforclinicalnutrition.com\/es-co\/#organization"},"image":{"@id":"https:\/\/lam.unitedforclinicalnutrition.com\/es-co\/bases-de-la-nutricion\/#primaryimage"},"thumbnailUrl":"https:\/\/lam.unitedforclinicalnutrition.com\/es-co\/wp-content\/uploads\/sites\/7\/2018\/06\/mood_nutrition_basics-2.jpg","articleSection":["Art\u00edculos","Nutrici\u00f3n Cl\u00ednica"],"inLanguage":"es-CO","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/lam.unitedforclinicalnutrition.com\/es-co\/bases-de-la-nutricion\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/lam.unitedforclinicalnutrition.com\/es-co\/bases-de-la-nutricion\/","url":"https:\/\/lam.unitedforclinicalnutrition.com\/es-co\/bases-de-la-nutricion\/","name":"Bases de la Nutrici\u00f3n - Unidos por la Nutrici\u00f3n Cl\u00ednica | Colombia","isPartOf":{"@id":"https:\/\/lam.unitedforclinicalnutrition.com\/es-co\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lam.unitedforclinicalnutrition.com\/es-co\/bases-de-la-nutricion\/#primaryimage"},"image":{"@id":"https:\/\/lam.unitedforclinicalnutrition.com\/es-co\/bases-de-la-nutricion\/#primaryimage"},"thumbnailUrl":"https:\/\/lam.unitedforclinicalnutrition.com\/es-co\/wp-content\/uploads\/sites\/7\/2018\/06\/mood_nutrition_basics-2.jpg","datePublished":"2015-03-31T00:00:00+00:00","dateModified":"2021-11-10T12:40:06+00:00","description":"Una dieta saludable est\u00e1 normalmente compuesta de macronutrientes, micronutrientes y l\u00edquidos. Cuando son consumidos de forma balanceada, normalmente","breadcrumb":{"@id":"https:\/\/lam.unitedforclinicalnutrition.com\/es-co\/bases-de-la-nutricion\/#breadcrumb"},"inLanguage":"es-CO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lam.unitedforclinicalnutrition.com\/es-co\/bases-de-la-nutricion\/"]}]},{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/lam.unitedforclinicalnutrition.com\/es-co\/bases-de-la-nutricion\/#primaryimage","url":"https:\/\/lam.unitedforclinicalnutrition.com\/es-co\/wp-content\/uploads\/sites\/7\/2018\/06\/mood_nutrition_basics-2.jpg","contentUrl":"https:\/\/lam.unitedforclinicalnutrition.com\/es-co\/wp-content\/uploads\/sites\/7\/2018\/06\/mood_nutrition_basics-2.jpg","width":856,"height":571},{"@type":"BreadcrumbList","@id":"https:\/\/lam.unitedforclinicalnutrition.com\/es-co\/bases-de-la-nutricion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/lam.unitedforclinicalnutrition.com\/es-co\/"},{"@type":"ListItem","position":2,"name":"Bases de la Nutrici\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/lam.unitedforclinicalnutrition.com\/es-co\/#website","url":"https:\/\/lam.unitedforclinicalnutrition.com\/es-co\/","name":"Unidos por la Nutrici\u00f3n Cl\u00ednica | Colombia","description":"Es una iniciativa creada por Fresenius Kabi para trabajar en conjunto con los profesionales de la salud.","publisher":{"@id":"https:\/\/lam.unitedforclinicalnutrition.com\/es-co\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lam.unitedforclinicalnutrition.com\/es-co\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CO"},{"@type":"Organization","@id":"https:\/\/lam.unitedforclinicalnutrition.com\/es-co\/#organization","name":"Fresenius Kabi AG","url":"https:\/\/lam.unitedforclinicalnutrition.com\/es-co\/","logo":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/lam.unitedforclinicalnutrition.com\/es-co\/#\/schema\/logo\/image\/","url":"https:\/\/lam.unitedforclinicalnutrition.com\/es-co\/wp-content\/uploads\/sites\/7\/2018\/06\/Downloads_en_0000_Logo_edit_spanish.jpg","contentUrl":"https:\/\/lam.unitedforclinicalnutrition.com\/es-co\/wp-content\/uploads\/sites\/7\/2018\/06\/Downloads_en_0000_Logo_edit_spanish.jpg","width":600,"height":400,"caption":"Fresenius Kabi AG"},"image":{"@id":"https:\/\/lam.unitedforclinicalnutrition.com\/es-co\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/lam.unitedforclinicalnutrition.com\/es-co\/#\/schema\/person\/047903fcf38a9d211770ad89bfd1360b","name":"actycrea","image":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/secure.gravatar.com\/avatar\/525bdeedb358bff65b8fc0b894d469f1ddd5b5113ca5c201756ec4f13ca61bdc?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/525bdeedb358bff65b8fc0b894d469f1ddd5b5113ca5c201756ec4f13ca61bdc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/525bdeedb358bff65b8fc0b894d469f1ddd5b5113ca5c201756ec4f13ca61bdc?s=96&d=mm&r=g","caption":"actycrea"}}]}},"_links":{"self":[{"href":"https:\/\/lam.unitedforclinicalnutrition.com\/es-co\/wp-json\/wp\/v2\/posts\/375","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lam.unitedforclinicalnutrition.com\/es-co\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lam.unitedforclinicalnutrition.com\/es-co\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lam.unitedforclinicalnutrition.com\/es-co\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lam.unitedforclinicalnutrition.com\/es-co\/wp-json\/wp\/v2\/comments?post=375"}],"version-history":[{"count":0,"href":"https:\/\/lam.unitedforclinicalnutrition.com\/es-co\/wp-json\/wp\/v2\/posts\/375\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lam.unitedforclinicalnutrition.com\/es-co\/wp-json\/wp\/v2\/media\/516"}],"wp:attachment":[{"href":"https:\/\/lam.unitedforclinicalnutrition.com\/es-co\/wp-json\/wp\/v2\/media?parent=375"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lam.unitedforclinicalnutrition.com\/es-co\/wp-json\/wp\/v2\/categories?post=375"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lam.unitedforclinicalnutrition.com\/es-co\/wp-json\/wp\/v2\/tags?post=375"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}